{"id":69329,"date":"2025-12-24T05:48:04","date_gmt":"2025-12-24T05:48:04","guid":{"rendered":"http:\/\/localhost\/!projects\/!webs\/thebiography.org\/lex-scott-davis-biografie-ethnizitat-ehemann-kinder\/"},"modified":"2025-08-28T02:29:43","modified_gmt":"2025-08-28T02:29:43","slug":"lex-scott-davis-biografie-ethnizitat-ehemann-kinder","status":"publish","type":"post","link":"https:\/\/thebiography.org\/de\/lex-scott-davis-biografie-ethnizitat-ehemann-kinder\/","title":{"rendered":"Lex Scott Davis\u2018 Biografie: Ethnizit\u00e4t, Ehemann, Kinder"},"content":{"rendered":"<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_77 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Table of Contents<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Toggle Table of Content\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 eztoc-toggle-hide-by-default' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/thebiography.org\/de\/lex-scott-davis-biografie-ethnizitat-ehemann-kinder\/#Welche_ethnische_Zugehoerigkeit_hat_Lex_Scott_Davis\" >Welche ethnische Zugeh\u00f6rigkeit hat Lex Scott Davis?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/thebiography.org\/de\/lex-scott-davis-biografie-ethnizitat-ehemann-kinder\/#Kindheit_und_Bildung\" >Kindheit und Bildung<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/thebiography.org\/de\/lex-scott-davis-biografie-ethnizitat-ehemann-kinder\/#Rollen_in_Filmen\" >Rollen in Filmen<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/thebiography.org\/de\/lex-scott-davis-biografie-ethnizitat-ehemann-kinder\/#Rollen_in_Fernsehserien\" >Rollen in Fernsehserien<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/thebiography.org\/de\/lex-scott-davis-biografie-ethnizitat-ehemann-kinder\/#Weitere_Mitwirkende\" >Weitere Mitwirkende<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/thebiography.org\/de\/lex-scott-davis-biografie-ethnizitat-ehemann-kinder\/#Ehemann_und_Kinder\" >Ehemann und Kinder<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https:\/\/thebiography.org\/de\/lex-scott-davis-biografie-ethnizitat-ehemann-kinder\/#Hobbys_und_andere_Interessen\" >Hobbys und andere Interessen<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-8\" href=\"https:\/\/thebiography.org\/de\/lex-scott-davis-biografie-ethnizitat-ehemann-kinder\/#Alter_Groesse_und_Vermoegen\" >Alter, Gr\u00f6\u00dfe und Verm\u00f6gen<\/a><\/li><\/ul><\/nav><\/div>\n<h2><span class=\"ez-toc-section\" id=\"Welche_ethnische_Zugehoerigkeit_hat_Lex_Scott_Davis\"><\/span>Welche ethnische Zugeh\u00f6rigkeit hat Lex Scott Davis?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Alexis Scott \u2018Lex\u2019 Davis wurde am 21. Februar 1991 in Baltimore, Maryland, USA geboren \u2013 ihr Sternzeichen ist Fische, sie besitzt die amerikanische Staatsb\u00fcrgerschaft und ihre ethnische Zugeh\u00f6rigkeit ist afroamerikanisch. Sie ist eine Schauspielerin, die wahrscheinlich am besten f\u00fcr ihre Darstellung von Nya, einer der Hauptfiguren in dem Action-Science-Fiction-Horrorfilm \u201eThe First Purge\u201c aus dem Jahr 2018 bekannt ist, geschrieben von James DeMonaco, inszeniert von Gerard McMurray und mit Y\u2019lan Noel und Joivan Wade in den Hauptrollen. Der Film handelt von der herrschenden amerikanischen politischen Partei, die ein Experiment durchf\u00fchrt, bei dem f\u00fcr 12 Stunden keine Gesetze auf Staten Island gelten, und diejenigen, die sich entscheiden, dort zu bleiben, 5.000 Dollar erhalten. Der Film wurde f\u00fcr einen Imagine Games Network (IGN) Summer Movie Award als bester Actionfilm nominiert. Sie ist eine <a rel=\"nofollow\" href=\"https:\/\/dollface.fandom.com\/wiki\/Lex_Scott_Davis\" target=\"_blank\">Schauspielerin<\/a>.<\/p>\n<p>https:\/\/www.instagram.com\/p\/8lQu3kR-HW\/<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Kindheit_und_Bildung\"><\/span>Kindheit und Bildung<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Lex wuchs in Baltimore bei ihrem Vater auf, der Inhaber einer Immobilienfirma ist, und ihrer Mutter, die Life Coach ist. Lex hat nie etwas \u00fcber Geschwister erz\u00e4hlt, und man geht daher davon aus, dass sie ein Einzelkind ist.<\/p>\n<p>Sie wuchs mit Interesse am <a rel=\"nofollow\" href=\"https:\/\/horror.fandom.com\/wiki\/Lex_Scott_Davis\" target=\"_blank\">Schauspiel<\/a> auf und trat in einigen Theaterst\u00fccken auf, die an ihrer Highschool und einem lokalen Theater aufgef\u00fchrt wurden. Ihre Eltern dr\u00e4ngten Lex jedoch, sich auf ihr Studium zu konzentrieren, anstatt eine Schauspielkarriere zu verfolgen. Nach ihrem Schulabschluss im Jahr 2009 schrieb sie sich an der Drexel University ein, wo sie 2013 einen Bachelor-Abschluss in Tanz und Physiotherapie erwarb. Anschlie\u00dfend zog Lex nach New York City, um an der New York Film Academy Schauspiel zu studieren.<\/p>\n<p><script async src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8220363953005131\" crossorigin=\"anonymous\"><\/script>\r\n<!-- TheBiography.org res1 -->\r\n<ins class=\"adsbygoogle\"\r\n     style=\"display:block\"\r\n     data-ad-client=\"ca-pub-8220363953005131\"\r\n     data-ad-slot=\"3620885119\"\r\n     data-ad-format=\"auto\"\r\n     data-full-width-responsive=\"true\"><\/ins>\r\n<script>\r\n     (adsbygoogle = window.adsbygoogle || []).push({});\r\n<\/script>\r\n<amp-ad layout=\"fixed-height\" height=300 type=\"adsense\" data-ad-client=\"ca-pub-8220363953005131\" data-ad-slot=\"3620885119\"><\/amp-ad>\r\n<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Rollen_in_Filmen\"><\/span>Rollen in Filmen<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Lex begann ihre Schauspielkarriere im Jahr 2014, als sie in zwei Kurzfilmen mitspielte: dem Krimidrama \u201eTwo Strangers\u201c und der Familienkom\u00f6die \u201eColorBlind\u201c.<\/p>\n<p>Sie erlangte Bekanntheit, als sie f\u00fcr die Hauptrolle als Toni Braxton in dem biografischen Musikdrama \u201eToni Braxton: Unbreak My Heart\u201c aus dem Jahr 2016 besetzt wurde, das auf dem Buch von Toni basiert und von Vondie Curtis-Hall inszeniert wurde. Es folgt dem Leben der ber\u00fchmten S\u00e4ngerin, Songwriterin und Musikproduzentin Toni Braxton, und der Film gewann vier Auszeichnungen und wurde f\u00fcr eine weitere nominiert.<\/p>\n<p>Im selben Jahr spielte <a rel=\"nofollow\" href=\"https:\/\/en.wikipedia.org\/wiki\/Lex_Scott_Davis\" target=\"_blank\">Lex<\/a> die Sasha in dem Kurzfilm-Drama \u201eThe Reunion\u201c, und ihre n\u00e4chste Rolle kam zwei Jahre sp\u00e4ter, als sie eingeladen wurde, Georgia in dem Action-Crime-Thriller \u201eSuperFly\u201c zu spielen, mit Lex, Jason Mitchell und Trevor Jackson in den Hauptrollen, der einen erfolgreichen Drogenh\u00e4ndler verfolgt, w\u00e4hrend er sich entscheidet, einen letzten gro\u00dfen Job zu machen, bevor er in den Ruhestand geht.<\/p>\n<p><iframe title=\"Lex Scott Davis Talks Multi-Dimensional &#039;Superfly&#039; Role | VIBE\" width=\"770\" height=\"433\" src=\"https:\/\/www.youtube.com\/embed\/Ze08sdCds30?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n<p>Im Jahr 2019 spielte Lex die Rolle der Keisha James an der Seite von Matthew Modine und Shane Paul McGhie im Mystery-Thriller-Drama \u201eFoster Boy\u201c, der von einem m\u00e4chtigen Anwalt und einem Jungen handelt, der in der Pflegefamilie misshandelt wurde, als sie sich zusammentun, um genau dieses System zu Fall zu bringen. Der Film gewann sieben Auszeichnungen und war f\u00fcr zwei weitere nominiert.<\/p>\n<p>Lex\u2019 j\u00fcngste Rolle in einem Film war in dem biografischen Drama \u201eSon of the South\u201c aus dem Jahr 2020, das auf der Autobiografie \u201eThe Wrong Side of Murder Creek\u201c von Bob Zellner basiert.<\/p>\n<p>Sie hat gerade erst die Dreharbeiten f\u00fcr das Drama \u201eFor Love\u201c abgeschlossen und dreht derzeit f\u00fcr zwei Filme: den Actionfilm \u201eSweet Girl\u201c und die Thriller-Kom\u00f6die \u201eA Lot of Nothing\u201c.<\/p>\n<p><script async src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8220363953005131\" crossorigin=\"anonymous\"><\/script>\r\n<!-- TheBiography.org res2 -->\r\n<ins class=\"adsbygoogle\"\r\n     style=\"display:block\"\r\n     data-ad-client=\"ca-pub-8220363953005131\"\r\n     data-ad-slot=\"8502510853\"\r\n     data-ad-format=\"auto\"\r\n     data-full-width-responsive=\"true\"><\/ins>\r\n<script>\r\n     (adsbygoogle = window.adsbygoogle || []).push({});\r\n<\/script>\r\n<amp-ad layout=\"fixed-height\" height=300 type=\"adsense\" data-ad-client=\"ca-pub-8220363953005131\" data-ad-slot=\"8502510853\"><\/amp-ad>\r\n<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Rollen_in_Fernsehserien\"><\/span>Rollen in Fernsehserien<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Lex hatte ihr Fernsehdeb\u00fct 2015, als sie f\u00fcr die Rolle der Kellnerin in der Episode \u201eAlong Came Holly\u201c der Comedy-Serie \u201eThe Exes\u201c besetzt wurde, und erlangte 2017 Anerkennung, als sie Alyse Craig in acht Episoden des Action-Crime-Dramas \u201eTraining Day\u201c spielte, das von Will Beall geschaffen wurde und Bill Paxton, Justin Cornwell und Katrina Law in den Hauptrollen hatte. Die Serie folgt einem neuen Polizisten, der mit einem korrupten Beamten zusammenarbeitet, und wurde f\u00fcr zwei Auszeichnungen nominiert.<\/p>\n<p>Lex hatte danach eine einmalige Gastrolle in einer Episode der Serie \u201eTales\u201c im Jahr 2017 und wurde anschlie\u00dfend f\u00fcr die Hauptrolle in der Comedy-Serie \u201eUntitled Coley Mustafa Speaks Project\u201c besetzt, die sie auch produzierte, aber von keinem Sender aufgegriffen wurde. Im Jahr 2020 verk\u00f6rperte sie <a rel=\"nofollow\" href=\"https:\/\/www.imdb.com\/name\/nm6280112\/\" target=\"_blank\">Quiara Thompson<\/a> in f\u00fcnf Episoden der Serie \u201eThe L Word: Generation Q\u201c, in der Jennifer Beals, Katherine Moennig und Leisha Hailey mitspielten.<\/p>\n<figure id=\"attachment_3880\" aria-describedby=\"caption-attachment-3880\" style=\"width: 732px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-3880\" src=\"https:\/\/thebiography.org\/wp-content\/uploads\/2021\/02\/wp3726944-732x1024.jpg\" alt=\"\" width=\"732\" height=\"1024\" srcset=\"\/\/thebiography.org\/wp-content\/uploads\/2021\/02\/wp3726944-732x1024.jpg 732w, \/\/thebiography.org\/wp-content\/uploads\/2021\/02\/wp3726944-215x300.jpg 215w, \/\/thebiography.org\/wp-content\/uploads\/2021\/02\/wp3726944-1098x1536.jpg 1098w, \/\/thebiography.org\/wp-content\/uploads\/2021\/02\/wp3726944-175x245.jpg 175w, \/\/thebiography.org\/wp-content\/uploads\/2021\/02\/wp3726944-450x629.jpg 450w, \/\/thebiography.org\/wp-content\/uploads\/2021\/02\/wp3726944-1170x1636.jpg 1170w, \/\/thebiography.org\/wp-content\/uploads\/2021\/02\/wp3726944-768x1074.jpg 768w, \/\/thebiography.org\/wp-content\/uploads\/2021\/02\/wp3726944.jpg 1200w\" sizes=\"auto, (max-width: 732px) 100vw, 732px\" \/><figcaption id=\"caption-attachment-3880\" class=\"wp-caption-text\"><a href=\"https:\/\/wallpapercave.com\/wp\/wp3726944.jpg\" target=\"_blank\" rel=\"nofollow noopener\">Lex Scott Davis<\/a><\/figcaption><\/figure>\n<p>Lex\u2019 j\u00fcngste Rolle in einer Fernsehserie war in der Folge \u201eDancing at Los Angeles\u201c der Dramaserie \u201eAll Rise\u201c aus dem Jahr 2020, die f\u00fcr sieben Auszeichnungen nominiert und mit einer ausgezeichnet wurde.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Weitere_Mitwirkende\"><\/span>Weitere Mitwirkende<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Lex hat auch eine einzige Schreibgutschrift \u2013 im Jahr 2014 schrieb sie gemeinsam den Kurzfilm \u201eColor Blind\u201c.<\/p>\n<p>Sie war au\u00dferdem in drei Talkshows zu sehen: \u201eMade in Hollywood\u201c und \u201eComplex x Fuse\u201c beide im Jahr 2018 sowie \u201eChasing Hollywood\u201c im Jahr 2019.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Ehemann_und_Kinder\"><\/span>Ehemann und Kinder<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Lex heiratete ihre bessere H\u00e4lfte Mo McRae am 21. Juli 2019, nachdem sie etwa zwei Jahre lang zusammen waren und weniger als ein Jahr verlobt waren.<\/p>\n<p><script async src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8220363953005131\" crossorigin=\"anonymous\"><\/script>\r\n<!-- TheBiography.org res3 -->\r\n<ins class=\"adsbygoogle\"\r\n     style=\"display:block\"\r\n     data-ad-client=\"ca-pub-8220363953005131\"\r\n     data-ad-slot=\"1812684276\"\r\n     data-ad-format=\"auto\"\r\n     data-full-width-responsive=\"true\"><\/ins>\r\n<script>\r\n     (adsbygoogle = window.adsbygoogle || []).push({});\r\n<\/script>\r\n<amp-ad layout=\"fixed-height\" height=300 type=\"adsense\" data-ad-client=\"ca-pub-8220363953005131\" data-ad-slot=\"1812684276\"><\/amp-ad>\r\n<\/p>\n<p>Ihre Hochzeit war &#8222;unplugged&#8220;, das hei\u00dft, den G\u00e4sten war die Nutzung elektronischer Ger\u00e4te jeglicher Art nicht erlaubt. Lex und <a rel=\"nofollow\" href=\"https:\/\/en.wikipedia.org\/wiki\/Mo_McRae\" target=\"_blank\">Mo<\/a> lernten sich am Set von &#8222;The First Purge&#8220; kennen und begannen nur wenige Tage sp\u00e4ter, sich zu daten. Die beiden haben keine gemeinsamen Kinder, da beide sich derzeit auf ihre Karrieren konzentrieren m\u00f6chten.<\/p>\n<p>Mo McRae wurde am 4. Juli 1982 in Los Angeles, Kalifornien, USA geboren \u2013 sein Sternzeichen ist Krebs und er besitzt die amerikanische Staatsb\u00fcrgerschaft. Er ist Schauspieler, Filmautor und Produzent, der vor allem f\u00fcr seine Darstellung des Tyler in dem Krimi-Thriller \u201eSons of Anarchy\u201c bekannt sein k\u00f6nnte, der ein gro\u00dfer Erfolg war und 11 Auszeichnungen gewann, darunter einen Golden Globe, und f\u00fcr 55 weitere Auszeichnungen nominiert wurde.<\/p>\n<div id='gallery-2' class='gallery galleryid-69329 gallery-columns-4 gallery-size-thumbnail'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/thebiography.org\/wp-content\/uploads\/2021\/02\/1-3.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"data:image\/svg+xml;base64,PHN2ZyB2aWV3Qm94PScwIDAgMTUwIDE1MCcgeG1sbnM9J2h0dHA6Ly93d3cudzMub3JnLzIwMDAvc3ZnJz48L3N2Zz4=\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-src=\"https:\/\/thebiography.org\/wp-content\/uploads\/2021\/02\/1-3-150x150.jpg\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/thebiography.org\/wp-content\/uploads\/2021\/02\/110217-shows-Tales-Ep-107-18.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"data:image\/svg+xml;base64,PHN2ZyB2aWV3Qm94PScwIDAgMTUwIDE1MCcgeG1sbnM9J2h0dHA6Ly93d3cudzMub3JnLzIwMDAvc3ZnJz48L3N2Zz4=\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-src=\"https:\/\/thebiography.org\/wp-content\/uploads\/2021\/02\/110217-shows-Tales-Ep-107-18-150x150.jpg\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/thebiography.org\/wp-content\/uploads\/2021\/02\/28294141b9088f5986edda0f3fba6ce7.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"data:image\/svg+xml;base64,PHN2ZyB2aWV3Qm94PScwIDAgMTUwIDE1MCcgeG1sbnM9J2h0dHA6Ly93d3cudzMub3JnLzIwMDAvc3ZnJz48L3N2Zz4=\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-src=\"https:\/\/thebiography.org\/wp-content\/uploads\/2021\/02\/28294141b9088f5986edda0f3fba6ce7-150x150.jpg\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/thebiography.org\/wp-content\/uploads\/2021\/02\/lex-scott-davis-by-mo-mcrae.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"data:image\/svg+xml;base64,PHN2ZyB2aWV3Qm94PScwIDAgMTUwIDE1MCcgeG1sbnM9J2h0dHA6Ly93d3cudzMub3JnLzIwMDAvc3ZnJz48L3N2Zz4=\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-src=\"https:\/\/thebiography.org\/wp-content\/uploads\/2021\/02\/lex-scott-davis-by-mo-mcrae-150x150.jpg\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\n<p>Zwei seiner weiteren bemerkenswerten Leistungen waren in dem Sportdrama \u201eGridiron Gang\u201c aus dem Jahr 2006 mit Dwayne \u2018The Rock\u2019 Johnson in der Hauptrolle und in der Dramaserie \u201ePitch\u201c aus dem Jahr 2016.<\/p>\n<p>Lex hat nicht \u00fcber andere M\u00e4nner gesprochen, die sie m\u00f6glicherweise gedatet hat, daher ist sie, Stand Januar 2021, mit Mo McRae verheiratet und hat keine Kinder.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Hobbys_und_andere_Interessen\"><\/span>Hobbys und andere Interessen<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Lex ist eine Feministin, die seit Beginn ihrer Schauspielkarriere f\u00fcr Frauenrechte und Gleichberechtigung k\u00e4mpft und sich derzeit haupts\u00e4chlich darauf konzentriert, Frauen in Baltimore zu st\u00e4rken.<\/p>\n<p>Sie probiert gerne verschiedene K\u00fcchen und bevorzugt Meeresfr\u00fcchte \u00fcber alles, besonders Salat mit Meeresfr\u00fcchten. Lex wurde ein Fan des Salats, als ihre Tante ihr ihr eigenes, einzigartiges Rezept gab.<\/p>\n<p><script async src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8220363953005131\" crossorigin=\"anonymous\"><\/script>\r\n<!-- TheBiography.org res4 -->\r\n<ins class=\"adsbygoogle\"\r\n     style=\"display:block\"\r\n     data-ad-client=\"ca-pub-8220363953005131\"\r\n     data-ad-slot=\"7189429181\"\r\n     data-ad-format=\"auto\"\r\n     data-full-width-responsive=\"true\"><\/ins>\r\n<script>\r\n     (adsbygoogle = window.adsbygoogle || []).push({});\r\n<\/script>\r\n<amp-ad layout=\"fixed-height\" height=300 type=\"adsense\" data-ad-client=\"ca-pub-8220363953005131\" data-ad-slot=\"7189429181\"><\/amp-ad>\r\n<\/p>\n<p>Sie ist ein Fan von T\u00e4towierungen und hat mehrere, von denen einige auf ihrer linken Hand sichtbar sind.<\/p>\n<p>Lex ist ein riesiger Musikfan und liebt es zu tanzen. Sie begann mit zwei Jahren zu tanzen und hat seitdem an verschiedenen Wettbewerben teilgenommen, von denen sie mehrere gewonnen hat.<\/p>\n<p>In ihrer Freizeit schaut sich Lex gerne Filme mit ihren Lieblingsschauspielern und -schauspielerinnen Jim Carrey, Brad Pitt und Anne Hathaway an, wie zum Beispiel die Kom\u00f6die \u201eBruce Almighty\u201c, das romantische Drama \u201eMeet Joe Black\u201c und das historische Musikdrama \u201eLes Mis\u00e9rables\u201c.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Alter_Groesse_und_Vermoegen\"><\/span>Alter, Gr\u00f6\u00dfe und Verm\u00f6gen<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Lex ist 29 Jahre alt. Sie hat lange schwarze Haare und braune Augen, ist 1,60 m gro\u00df und wiegt etwa 54 kg.<\/p>\n<p>Ab Januar 2021 wurde ihr Verm\u00f6gen auf \u00fcber 1 Million US-Dollar <a rel=\"nofollow\" href=\"https:\/\/www.tvovermind.com\/lex-scott-davis\/\" target=\"_blank\">gesch\u00e4tzt<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Welche ethnische Zugeh\u00f6rigkeit hat Lex Scott Davis? Alexis Scott \u2018Lex\u2019 Davis wurde am 21. Februar 1991 in Baltimore, Maryland, USA geboren \u2013 ihr Sternzeichen ist Fische, sie besitzt die amerikanische Staatsb\u00fcrgerschaft und ihre ethnische Zugeh\u00f6rigkeit ist afroamerikanisch. Sie ist eine Schauspielerin, die wahrscheinlich am besten f\u00fcr ihre Darstellung von Nya, einer der Hauptfiguren in dem<\/p>\n","protected":false},"author":1,"featured_media":37678,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ep_exclude_from_search":false,"amp_status":"","footnotes":""},"categories":[6579],"tags":[],"class_list":{"0":"post-69329","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-schauspieler"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Lex Scott Davis\u2018 Biografie: Ethnizit\u00e4t, Ehemann, Kinder<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/thebiography.org\/de\/lex-scott-davis-biografie-ethnizitat-ehemann-kinder\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Lex Scott Davis\u2018 Biografie: Ethnizit\u00e4t, Ehemann, Kinder\" \/>\n<meta property=\"og:description\" content=\"Welche ethnische Zugeh\u00f6rigkeit hat Lex Scott Davis? Alexis Scott \u2018Lex\u2019 Davis wurde am 21. Februar 1991 in Baltimore, Maryland, USA geboren \u2013 ihr Sternzeichen ist Fische, sie besitzt die amerikanische Staatsb\u00fcrgerschaft und ihre ethnische Zugeh\u00f6rigkeit ist afroamerikanisch. Sie ist eine Schauspielerin, die wahrscheinlich am besten f\u00fcr ihre Darstellung von Nya, einer der Hauptfiguren in dem\" \/>\n<meta property=\"og:url\" content=\"https:\/\/thebiography.org\/de\/lex-scott-davis-biografie-ethnizitat-ehemann-kinder\/\" \/>\n<meta property=\"og:site_name\" content=\"The Biography\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/daniel.wanburg\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-12-24T05:48:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/thebiography.org\/wp-content\/uploads\/2021\/02\/Romo-IRISLex4a.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1084\" \/>\n\t<meta property=\"og:image:height\" content=\"542\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Daniel Wanburg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Daniel Wanburg\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"6\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/thebiography.org\/de\/lex-scott-davis-biografie-ethnizitat-ehemann-kinder\/\",\"url\":\"https:\/\/thebiography.org\/de\/lex-scott-davis-biografie-ethnizitat-ehemann-kinder\/\",\"name\":\"Lex Scott Davis\u2018 Biografie: Ethnizit\u00e4t, Ehemann, Kinder\",\"isPartOf\":{\"@id\":\"https:\/\/thebiography.org\/de\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/thebiography.org\/de\/lex-scott-davis-biografie-ethnizitat-ehemann-kinder\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/thebiography.org\/de\/lex-scott-davis-biografie-ethnizitat-ehemann-kinder\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/thebiography.org\/wp-content\/uploads\/2021\/02\/Romo-IRISLex4a.jpg\",\"datePublished\":\"2025-12-24T05:48:04+00:00\",\"author\":{\"@id\":\"https:\/\/thebiography.org\/de\/#\/schema\/person\/1d126e3e6e3c48b3ff869d116a4fbc1c\"},\"breadcrumb\":{\"@id\":\"https:\/\/thebiography.org\/de\/lex-scott-davis-biografie-ethnizitat-ehemann-kinder\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/thebiography.org\/de\/lex-scott-davis-biografie-ethnizitat-ehemann-kinder\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/thebiography.org\/de\/lex-scott-davis-biografie-ethnizitat-ehemann-kinder\/#primaryimage\",\"url\":\"https:\/\/thebiography.org\/wp-content\/uploads\/2021\/02\/Romo-IRISLex4a.jpg\",\"contentUrl\":\"https:\/\/thebiography.org\/wp-content\/uploads\/2021\/02\/Romo-IRISLex4a.jpg\",\"width\":1084,\"height\":542,\"caption\":\"Lex Scott Davis\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/thebiography.org\/de\/lex-scott-davis-biografie-ethnizitat-ehemann-kinder\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/thebiography.org\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Lex Scott Davis\u2018 Biografie: Ethnizit\u00e4t, Ehemann, Kinder\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/thebiography.org\/de\/#website\",\"url\":\"https:\/\/thebiography.org\/de\/\",\"name\":\"The Biography\",\"description\":\"Relationships, Net Worth, Measurements\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/thebiography.org\/de\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/thebiography.org\/de\/#\/schema\/person\/1d126e3e6e3c48b3ff869d116a4fbc1c\",\"name\":\"Daniel Wanburg\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/thebiography.org\/de\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/ea3e6e37b405aa3457baa18b3ae51ab5564d43737a0427463d5d20892d4d11b9?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/ea3e6e37b405aa3457baa18b3ae51ab5564d43737a0427463d5d20892d4d11b9?s=96&d=mm&r=g\",\"caption\":\"Daniel Wanburg\"},\"description\":\"As Managing Editor at The Biography, I oversee a skilled team to produce insightful biographies of influential figures. My responsibilities include managing the editorial process, conducting detailed research, crafting engaging narratives, and ensuring the accuracy and quality of our content. At The Biography, we aim to deliver in-depth profiles that provide valuable insights into the realms of business, entertainment, and more. Our commitment to meticulous research and dynamic storytelling highlights the significant journeys and successes of inspiring individuals.\",\"sameAs\":[\"https:\/\/www.facebook.com\/daniel.wanburg\/\",\"https:\/\/www.linkedin.com\/in\/daniel-wanburg-618177164\/\"],\"url\":\"https:\/\/thebiography.org\/de\/author\/admin\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Lex Scott Davis\u2018 Biografie: Ethnizit\u00e4t, Ehemann, Kinder","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/thebiography.org\/de\/lex-scott-davis-biografie-ethnizitat-ehemann-kinder\/","og_locale":"de_DE","og_type":"article","og_title":"Lex Scott Davis\u2018 Biografie: Ethnizit\u00e4t, Ehemann, Kinder","og_description":"Welche ethnische Zugeh\u00f6rigkeit hat Lex Scott Davis? Alexis Scott \u2018Lex\u2019 Davis wurde am 21. Februar 1991 in Baltimore, Maryland, USA geboren \u2013 ihr Sternzeichen ist Fische, sie besitzt die amerikanische Staatsb\u00fcrgerschaft und ihre ethnische Zugeh\u00f6rigkeit ist afroamerikanisch. Sie ist eine Schauspielerin, die wahrscheinlich am besten f\u00fcr ihre Darstellung von Nya, einer der Hauptfiguren in dem","og_url":"https:\/\/thebiography.org\/de\/lex-scott-davis-biografie-ethnizitat-ehemann-kinder\/","og_site_name":"The Biography","article_author":"https:\/\/www.facebook.com\/daniel.wanburg\/","article_published_time":"2025-12-24T05:48:04+00:00","og_image":[{"width":1084,"height":542,"url":"https:\/\/thebiography.org\/wp-content\/uploads\/2021\/02\/Romo-IRISLex4a.jpg","type":"image\/jpeg"}],"author":"Daniel Wanburg","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Daniel Wanburg","Gesch\u00e4tzte Lesezeit":"6\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/thebiography.org\/de\/lex-scott-davis-biografie-ethnizitat-ehemann-kinder\/","url":"https:\/\/thebiography.org\/de\/lex-scott-davis-biografie-ethnizitat-ehemann-kinder\/","name":"Lex Scott Davis\u2018 Biografie: Ethnizit\u00e4t, Ehemann, Kinder","isPartOf":{"@id":"https:\/\/thebiography.org\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/thebiography.org\/de\/lex-scott-davis-biografie-ethnizitat-ehemann-kinder\/#primaryimage"},"image":{"@id":"https:\/\/thebiography.org\/de\/lex-scott-davis-biografie-ethnizitat-ehemann-kinder\/#primaryimage"},"thumbnailUrl":"https:\/\/thebiography.org\/wp-content\/uploads\/2021\/02\/Romo-IRISLex4a.jpg","datePublished":"2025-12-24T05:48:04+00:00","author":{"@id":"https:\/\/thebiography.org\/de\/#\/schema\/person\/1d126e3e6e3c48b3ff869d116a4fbc1c"},"breadcrumb":{"@id":"https:\/\/thebiography.org\/de\/lex-scott-davis-biografie-ethnizitat-ehemann-kinder\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/thebiography.org\/de\/lex-scott-davis-biografie-ethnizitat-ehemann-kinder\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/thebiography.org\/de\/lex-scott-davis-biografie-ethnizitat-ehemann-kinder\/#primaryimage","url":"https:\/\/thebiography.org\/wp-content\/uploads\/2021\/02\/Romo-IRISLex4a.jpg","contentUrl":"https:\/\/thebiography.org\/wp-content\/uploads\/2021\/02\/Romo-IRISLex4a.jpg","width":1084,"height":542,"caption":"Lex Scott Davis"},{"@type":"BreadcrumbList","@id":"https:\/\/thebiography.org\/de\/lex-scott-davis-biografie-ethnizitat-ehemann-kinder\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/thebiography.org\/de\/"},{"@type":"ListItem","position":2,"name":"Lex Scott Davis\u2018 Biografie: Ethnizit\u00e4t, Ehemann, Kinder"}]},{"@type":"WebSite","@id":"https:\/\/thebiography.org\/de\/#website","url":"https:\/\/thebiography.org\/de\/","name":"The Biography","description":"Relationships, Net Worth, Measurements","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/thebiography.org\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/thebiography.org\/de\/#\/schema\/person\/1d126e3e6e3c48b3ff869d116a4fbc1c","name":"Daniel Wanburg","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/thebiography.org\/de\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/ea3e6e37b405aa3457baa18b3ae51ab5564d43737a0427463d5d20892d4d11b9?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ea3e6e37b405aa3457baa18b3ae51ab5564d43737a0427463d5d20892d4d11b9?s=96&d=mm&r=g","caption":"Daniel Wanburg"},"description":"As Managing Editor at The Biography, I oversee a skilled team to produce insightful biographies of influential figures. My responsibilities include managing the editorial process, conducting detailed research, crafting engaging narratives, and ensuring the accuracy and quality of our content. At The Biography, we aim to deliver in-depth profiles that provide valuable insights into the realms of business, entertainment, and more. Our commitment to meticulous research and dynamic storytelling highlights the significant journeys and successes of inspiring individuals.","sameAs":["https:\/\/www.facebook.com\/daniel.wanburg\/","https:\/\/www.linkedin.com\/in\/daniel-wanburg-618177164\/"],"url":"https:\/\/thebiography.org\/de\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/thebiography.org\/de\/wp-json\/wp\/v2\/posts\/69329","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/thebiography.org\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/thebiography.org\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/thebiography.org\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/thebiography.org\/de\/wp-json\/wp\/v2\/comments?post=69329"}],"version-history":[{"count":0,"href":"https:\/\/thebiography.org\/de\/wp-json\/wp\/v2\/posts\/69329\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/thebiography.org\/de\/wp-json\/wp\/v2\/media\/37678"}],"wp:attachment":[{"href":"https:\/\/thebiography.org\/de\/wp-json\/wp\/v2\/media?parent=69329"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/thebiography.org\/de\/wp-json\/wp\/v2\/categories?post=69329"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/thebiography.org\/de\/wp-json\/wp\/v2\/tags?post=69329"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}