{"id":70313,"date":"2025-11-04T18:38:48","date_gmt":"2025-11-04T18:38:48","guid":{"rendered":"http:\/\/localhost\/!projects\/!webs\/thebiography.org\/angelique-boyers-biografie-ehemann-alter-vermogen-familie\/"},"modified":"2025-08-30T08:44:18","modified_gmt":"2025-08-30T08:44:18","slug":"angelique-boyers-biografie-ehemann-alter-vermogen-familie","status":"publish","type":"post","link":"https:\/\/thebiography.org\/de\/angelique-boyers-biografie-ehemann-alter-vermogen-familie\/","title":{"rendered":"Angelique Boyers Biografie: Ehemann, Alter, Verm\u00f6gen, Familie"},"content":{"rendered":"<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_77 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Table of Contents<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Toggle Table of Content\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 eztoc-toggle-hide-by-default' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/thebiography.org\/de\/angelique-boyers-biografie-ehemann-alter-vermogen-familie\/#Wer_ist_Angelique_Boyer\" >Wer ist Angelique Boyer?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/thebiography.org\/de\/angelique-boyers-biografie-ehemann-alter-vermogen-familie\/#Fruehes_Leben_und_Familie\" >Fr\u00fches Leben und Familie<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/thebiography.org\/de\/angelique-boyers-biografie-ehemann-alter-vermogen-familie\/#Schauspielkarriere\" >Schauspielkarriere<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/thebiography.org\/de\/angelique-boyers-biografie-ehemann-alter-vermogen-familie\/#Privatleben\" >Privatleben<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/thebiography.org\/de\/angelique-boyers-biografie-ehemann-alter-vermogen-familie\/#Kurz_ueber_Sebastian_Rulli\" >Kurz \u00fcber Sebastian Rulli.<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/thebiography.org\/de\/angelique-boyers-biografie-ehemann-alter-vermogen-familie\/#Unternehmertum\" >Unternehmertum<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https:\/\/thebiography.org\/de\/angelique-boyers-biografie-ehemann-alter-vermogen-familie\/#Koerperliche_Eigenschaften_und_Hobbys\" >K\u00f6rperliche Eigenschaften und Hobbys<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-8\" href=\"https:\/\/thebiography.org\/de\/angelique-boyers-biografie-ehemann-alter-vermogen-familie\/#Moechten_Sie_ihr_Vermoegen_wissen\" >M\u00f6chten Sie ihr Verm\u00f6gen wissen?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-9\" href=\"https:\/\/thebiography.org\/de\/angelique-boyers-biografie-ehemann-alter-vermogen-familie\/#Skandale_und_Kontroversen\" >Skandale und Kontroversen<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-10\" href=\"https:\/\/thebiography.org\/de\/angelique-boyers-biografie-ehemann-alter-vermogen-familie\/#Ist_sie_in_den_sozialen_Medien_aktiv\" >Ist sie in den sozialen Medien aktiv?<\/a><\/li><\/ul><\/nav><\/div>\n<h2><span class=\"ez-toc-section\" id=\"Wer_ist_Angelique_Boyer\"><\/span>Wer ist Angelique Boyer?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Angelique Boyer Rousseau <strong>\u00a0<\/strong> ist Schauspielerin und Model, bekannt f\u00fcr ihre Auftritte in verschiedenen mexikanischen Telenovelas und Fernsehserien, darunter \u201eRebelde\u201c, \u201eAmar a Muerte\u201c und \u201eLo Que la Vida Robo\u201c. Sie wurde am 4. Juli 1988 im Zeichen Krebs in Saint-Claude Jura, Frankreich, geboren und hat mexikanische und franz\u00f6sische Vorfahren. Bis Mitte 2021 ist sie 33 Jahre alt.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Fruehes_Leben_und_Familie\"><\/span>Fr\u00fches Leben und Familie<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Angelique wurde von Patrick Boyer und Sylvie Rousseau geboren; ihre Mutter stammt aus Mexiko, w\u00e4hrend ihr Vater Franzose ist. Im Alter von zwei Jahren zog sie mit ihrer Familie nach Mexiko, und was ihre Ausbildung betrifft, besuchte sie das <a rel=\"nofollow\" href=\"https:\/\/biographymask.com\/angelique-boyer\/\" target=\"_blank\">Centro de Educaci\u00f3n Art\u00edstica<\/a>. W\u00e4hrend ihres Aufwachsens zeigte sie eine Affinit\u00e4t zum Tanzen, Singen und Schauspielern; obwohl sie haupts\u00e4chlich f\u00fcr ihre Schauspielrollen bekannt ist, war sie im Alter von 18 Jahren Mitglied einer Gruppe namens \u201eRabanitos Verdes\u201c, was \u00fcbersetzt \u201eKleine gr\u00fcne Radieschen\u201c bedeutet.<\/p>\n<blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\">\n<p lang=\"es\" dir=\"ltr\">Los incre\u00edbles bikinis low cost con los que Angelique Boyer roba suspiros son mexicanos y amigables con el medio ambiente.?Checa todos sus looks: <a rel=\"nofollow\" href=\"https:\/\/t.co\/luTcpaXjSK\">https:\/\/t.co\/luTcpaXjSK<\/a><\/p>\n<p>?: <a rel=\"nofollow\" href=\"https:\/\/twitter.com\/Anboy88?ref_src=twsrc%5Etfw\">@Anboy88<\/a> <a rel=\"nofollow\" href=\"https:\/\/t.co\/bkJyJWcSMc\">pic.twitter.com\/bkJyJWcSMc<\/a><\/p>\n<p>&mdash; EstiloDF (@EstiloDF) <a rel=\"nofollow\" href=\"https:\/\/twitter.com\/EstiloDF\/status\/1377410631607943169?ref_src=twsrc%5Etfw\">April 1, 2021<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<p>Die Gruppe bestand aus sechs Mitgliedern, die Popularit\u00e4t erlangten, weil sie das Titellied der Kinder-Telenovela mit dem Titel \u201eMaria Belen\u201c sangen.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Schauspielkarriere\"><\/span>Schauspielkarriere<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Mit einem Talent f\u00fcr das Unterhaltungsgesch\u00e4ft gab sie ihr TV-Deb\u00fct in der Rolle der Anette in der Telenovela \u201eCorazones al Limite\u201c. 2004 ergatterte sie die wiederkehrende Rolle der Victoria &#8222;Vico&#8220; Paz Mill\u00e1n in der mexikanischen Version der Telenovela \u201eRebelde\u201c, die zu einem weltweiten Ph\u00e4nomen wurde und Millionen von Fans aufgrund ihres teengerechten Inhalts anzog. 2005 gr\u00fcndete Angelique zusammen mit ihren Co-Stars Zoraida Gomez und Estefania Villarreal innerhalb der Telenovela \u201eRebelde\u201c die Popgruppe \u201eC3Q\u2019S\u201c \u2013 das Trio ver\u00f6ffentlichte die Single \u201eNo Me Importa\u201c. Sie ist <a rel=\"nofollow\" href=\"https:\/\/en.wikipedia.org\/wiki\/Angelique_Boyer\" target=\"_blank\">Angelique<\/a>.<\/p>\n<p>Ihre n\u00e4chste Rolle kam 2007, als sie eingeladen wurde, die Rolle der Antagonistin Margarita in der Telenovela \u201eMuchacitas Como Tu\u201c an der Seite von Ariadne Diaz zu \u00fcbernehmen.<\/p>\n<p><script async src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8220363953005131\" crossorigin=\"anonymous\"><\/script>\r\n<!-- TheBiography.org res1 -->\r\n<ins class=\"adsbygoogle\"\r\n     style=\"display:block\"\r\n     data-ad-client=\"ca-pub-8220363953005131\"\r\n     data-ad-slot=\"3620885119\"\r\n     data-ad-format=\"auto\"\r\n     data-full-width-responsive=\"true\"><\/ins>\r\n<script>\r\n     (adsbygoogle = window.adsbygoogle || []).push({});\r\n<\/script>\r\n<amp-ad layout=\"fixed-height\" height=300 type=\"adsense\" data-ad-client=\"ca-pub-8220363953005131\" data-ad-slot=\"3620885119\"><\/amp-ad>\r\n<\/p>\n<p>Im selben Jahr gab sie ihr Filmdeb\u00fct in dem Horrorfilm mit dem Titel \u201eJ-ok\u2019el\u201c. Nach einer Folge in der psychologischen Thrillerserie \u201eMujeres Asesinas\u201c trat sie als wiederkehrende Figur in der Telenovela \u201eAlma De Hierro\u201c auf und verk\u00f6rperte Sandra \u201eSandy Hierro Jimenez\u201c.<\/p>\n<p>Im folgenden Jahr ergatterte sie die Hauptrolle in einer weiteren Telenovela, \u201eCorazon Salvaje\u201c, an der Seite von Sebastian Zurita. Ihre Darstellung des Zigeiderm\u00e4dchens Jimena brachte ihr zwei Nominierungen f\u00fcr die beste junge Schauspielerin bei den Premios TVyNovelas und den Premios People en Espanol ein.<\/p>\n<p>Im Jahr 2010 spielte sie die Hauptrolle in der Telenovela &#8222;<a rel=\"nofollow\" href=\"https:\/\/biographymask.com\/angelique-boyer\/\" target=\"_blank\">Theresa<\/a>&#8222;, einer Neuauflage der gleichnamigen Telenovela aus dem Jahr 1989. Die Serie begleitet die junge und intelligente Theresa auf ihrem Weg, der Armut zu entkommen und sich als wohlhabende Pers\u00f6nlichkeit mit hohem Status zu etablieren.<\/p>\n<figure id=\"attachment_16189\" aria-describedby=\"caption-attachment-16189\" style=\"width: 770px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-16189\" src=\"https:\/\/thebiography.org\/wp-content\/uploads\/2021\/06\/AngeliqueBoyer_2021-851x1024.png\" alt=\"\" width=\"770\" height=\"927\" srcset=\"\/\/thebiography.org\/wp-content\/uploads\/2021\/06\/AngeliqueBoyer_2021-851x1024.png 851w, \/\/thebiography.org\/wp-content\/uploads\/2021\/06\/AngeliqueBoyer_2021-249x300.png 249w, \/\/thebiography.org\/wp-content\/uploads\/2021\/06\/AngeliqueBoyer_2021-175x210.png 175w, \/\/thebiography.org\/wp-content\/uploads\/2021\/06\/AngeliqueBoyer_2021-450x541.png 450w, \/\/thebiography.org\/wp-content\/uploads\/2021\/06\/AngeliqueBoyer_2021-768x924.png 768w, \/\/thebiography.org\/wp-content\/uploads\/2021\/06\/AngeliqueBoyer_2021.png 1080w\" sizes=\"auto, (max-width: 770px) 100vw, 770px\" \/><figcaption id=\"caption-attachment-16189\" class=\"wp-caption-text\"><a href=\"https:\/\/upload.wikimedia.org\/wikipedia\/commons\/5\/5f\/AngeliqueBoyer_2021.png\" target=\"_blank\" rel=\"nofollow noopener\">Angelique Boyer<\/a><\/figcaption><\/figure>\n<p>Langsam machte sie sich in der Welt der mexikanischen Telenovelas einen Namen, und diese Rolle blieb nicht unbemerkt. Sie brachte Angelique verschiedene Nominierungen und vier Auszeichnungen als beste Schauspielerin ein.<\/p>\n<p>Im folgenden Jahr verk\u00f6rperte sie Elisa Casta\u00f1\u00f3n Bouvier in der Telenovela <a rel=\"nofollow\" href=\"https:\/\/en.wikipedia.org\/wiki\/Abismo_de_pasi%C3%B3n\" target=\"_blank\">Abismo de pasi\u00f3n<\/a> und erhielt Nominierungen und Auszeichnungen f\u00fcr ihre Darstellung. Im Jahr 2013 ergatterte sie ihre beliebteste und bekannteste Rolle als Montserrat Mendonza Giacinti in der Telenovela \u201eLo Que la Vida me Robo\u201c an der Seite von Sebastian Ruli und Luis Roberto Guzman.<\/p>\n<p>Drei Jahre sp\u00e4ter kehrte sie als identische Drillinge in der Seifenoper mit dem Titel \u201eTres Veces Ana\u201c auf die Leinwand zur\u00fcck und teilte sich erneut die Credits mit Sebastian Ruli.<\/p>\n<p><script async src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8220363953005131\" crossorigin=\"anonymous\"><\/script>\r\n<!-- TheBiography.org res2 -->\r\n<ins class=\"adsbygoogle\"\r\n     style=\"display:block\"\r\n     data-ad-client=\"ca-pub-8220363953005131\"\r\n     data-ad-slot=\"8502510853\"\r\n     data-ad-format=\"auto\"\r\n     data-full-width-responsive=\"true\"><\/ins>\r\n<script>\r\n     (adsbygoogle = window.adsbygoogle || []).push({});\r\n<\/script>\r\n<amp-ad layout=\"fixed-height\" height=300 type=\"adsense\" data-ad-client=\"ca-pub-8220363953005131\" data-ad-slot=\"8502510853\"><\/amp-ad>\r\n<\/p>\n<p>Im Jahr 2018 trat sie in der Telenovela \u201eAmar a Muerte\u201c auf, wo sie die Rolle der Lucia Borges spielte, und zu ihren j\u00fcngsten Rollen geh\u00f6ren Auftritte in zwei Telenovelas mit den Titeln \u201eImperio de Mentiras\u201c und \u201eVencer el Pasado\u201c.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Privatleben\"><\/span>Privatleben<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Bez\u00fcglich ihrer Beziehungshistorie datete sie 2006 Diego Boneta, und nach ihrer Trennung begann sie, sich mit dem amerikanischen Schauspieler Drew Roy zu treffen, Berichten zufolge hatte sie auch eine kurze Beziehung mit dem mexikanischen Schauspieler <a rel=\"nofollow\" href=\"https:\/\/www.whosdatedwho.com\/dating\/angelique-boyer\" target=\"_blank\">Sebastian Zurita<\/a>.<\/p>\n<p>Im Jahr 2011 war sie mit dem Produzenten Jose Alberto Castro liiert, aber nach einer dreij\u00e4hrigen Beziehung trennten sie sich 2014. W\u00e4hrend der Dreharbeiten zur Telenovela \u201eLo Que la Vida me Robo\u201c lernte sie den argentinischen Schauspieler und Model Sebastian Rulli kennen, und kurz nach ihrer Trennung von Jose begann sie, mit ihrem Co-Star auszugehen. Seitdem sind sie unzertrennlich. Nach ihren Instagram-Accounts zu urteilen, reisen sie gerne zusammen und bekennen ihre gegenseitige Liebe durch herzerw\u00e4rmende Bildunterschriften.<\/p>\n<p>https:\/\/www.youtube.com\/watch?v=bVpZabQloQE<\/p>\n<p>Das Paar dreht auch gerne kurze Sketche f\u00fcr TikTok. In einem Interview sagte Sebastian, dass sie derzeit keine Pl\u00e4ne bez\u00fcglich Heirat oder Kinder haben. Au\u00dferdem verriet er eine ungew\u00f6hnliche Angewohnheit von Angelique und sagte: \u201eSie raucht, aber ich verbiete ihr niemals, das zu tun. Wenn sie es braucht, wenn sie davon abh\u00e4ngig ist oder es nicht lassen will, ist nichts passiert. Es liegt nicht am Rauch, der mich st\u00f6rt. Er st\u00f6rt mich, aber es liegt nicht an mir, sondern daran, dass ich m\u00f6chte, dass sie gesund ist.\u201c<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Kurz_ueber_Sebastian_Rulli\"><\/span>Kurz \u00fcber Sebastian Rulli.<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Sebastian Rulli, der 45-j\u00e4hrige geb\u00fcrtige Argentinier, hat sich zusammen mit seiner Freundin als eines der bekanntesten Gesichter in der Welt der Telenovelas etabliert.<\/p>\n<p><script async src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8220363953005131\" crossorigin=\"anonymous\"><\/script>\r\n<!-- TheBiography.org res3 -->\r\n<ins class=\"adsbygoogle\"\r\n     style=\"display:block\"\r\n     data-ad-client=\"ca-pub-8220363953005131\"\r\n     data-ad-slot=\"1812684276\"\r\n     data-ad-format=\"auto\"\r\n     data-full-width-responsive=\"true\"><\/ins>\r\n<script>\r\n     (adsbygoogle = window.adsbygoogle || []).push({});\r\n<\/script>\r\n<amp-ad layout=\"fixed-height\" height=300 type=\"adsense\" data-ad-client=\"ca-pub-8220363953005131\" data-ad-slot=\"1812684276\"><\/amp-ad>\r\n<\/p>\n<p>Er begann seine Karriere 1995 und trat in \u00fcber 20 Telenovelas auf, wobei er zahlreiche Nominierungen und Auszeichnungen f\u00fcr seine schauspielerischen Leistungen erhielt. Zu seinen bekanntesten Rollen geh\u00f6ren Telenovelas wie \u201eRubi\u201c, \u201eCuando me Enamoro\u201c und \u201eUn Gancho de Corazon\u201c.<\/p>\n<p>Vor seiner Beziehung mit Angelique war er mit der Schauspielerin und Fernsehpers\u00f6nlichkeit Cecilia Galiano verheiratet, mit der er einen Sohn namens Santiago hat. Sie lie\u00dfen sich 2011 scheiden.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Unternehmertum\"><\/span>Unternehmertum<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Neben ihrer Schauspiel- und Modelkarriere hat die Schauspielerin ihr T\u00e4tigkeitsfeld erweitert und die Marke Nuba <a rel=\"nofollow\" href=\"https:\/\/nutricionbalanceada.mx\/productos\/\" target=\"_blank\">Nutricion Balanceada<\/a> mitgegr\u00fcndet, die verschiedene Nahrungserg\u00e4nzungsmittel wie Proteinpulver und proteinangereicherten Kaffee verkauft. Dieser unternehmerische Schritt ist nicht ungew\u00f6hnlich, da Angelique und ihr langj\u00e4hriger Freund gerne trainieren und auf ihre Ern\u00e4hrung achten.<\/p>\n<div id='gallery-2' class='gallery galleryid-70313 gallery-columns-5 gallery-size-thumbnail'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/thebiography.org\/wp-content\/uploads\/2021\/06\/download.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"data:image\/svg+xml;base64,PHN2ZyB2aWV3Qm94PScwIDAgMTUwIDE1MCcgeG1sbnM9J2h0dHA6Ly93d3cudzMub3JnLzIwMDAvc3ZnJz48L3N2Zz4=\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-src=\"https:\/\/thebiography.org\/wp-content\/uploads\/2021\/06\/download-150x150.jpg\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/thebiography.org\/wp-content\/uploads\/2021\/06\/angelique_boyer_crop1614058543135.jpg_423682103.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"data:image\/svg+xml;base64,PHN2ZyB2aWV3Qm94PScwIDAgMTUwIDE1MCcgeG1sbnM9J2h0dHA6Ly93d3cudzMub3JnLzIwMDAvc3ZnJz48L3N2Zz4=\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" data-srcset=\"\/\/thebiography.org\/wp-content\/uploads\/2021\/06\/angelique_boyer_crop1614058543135.jpg_423682103-150x150.jpg 150w, \/\/thebiography.org\/wp-content\/uploads\/2021\/06\/angelique_boyer_crop1614058543135.jpg_423682103-300x300.jpg 300w, \/\/thebiography.org\/wp-content\/uploads\/2021\/06\/angelique_boyer_crop1614058543135.jpg_423682103-1024x1024.jpg 1024w, \/\/thebiography.org\/wp-content\/uploads\/2021\/06\/angelique_boyer_crop1614058543135.jpg_423682103-175x175.jpg 175w, \/\/thebiography.org\/wp-content\/uploads\/2021\/06\/angelique_boyer_crop1614058543135.jpg_423682103-450x450.jpg 450w, \/\/thebiography.org\/wp-content\/uploads\/2021\/06\/angelique_boyer_crop1614058543135.jpg_423682103-1170x1170.jpg 1170w, \/\/thebiography.org\/wp-content\/uploads\/2021\/06\/angelique_boyer_crop1614058543135.jpg_423682103-768x768.jpg 768w, \/\/thebiography.org\/wp-content\/uploads\/2021\/06\/angelique_boyer_crop1614058543135.jpg_423682103.jpg 1200w\" data-src=\"https:\/\/thebiography.org\/wp-content\/uploads\/2021\/06\/angelique_boyer_crop1614058543135.jpg_423682103-150x150.jpg\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/thebiography.org\/wp-content\/uploads\/2021\/06\/angelique_boyer02.jpg_242310155.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"data:image\/svg+xml;base64,PHN2ZyB2aWV3Qm94PScwIDAgMTUwIDE1MCcgeG1sbnM9J2h0dHA6Ly93d3cudzMub3JnLzIwMDAvc3ZnJz48L3N2Zz4=\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-src=\"https:\/\/thebiography.org\/wp-content\/uploads\/2021\/06\/angelique_boyer02.jpg_242310155-150x150.jpg\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/thebiography.org\/wp-content\/uploads\/2021\/06\/10-Angelique-Boyer-Movies-and-TV-Shows-Rated-From-Best-To-Worst-1200x675-1.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"data:image\/svg+xml;base64,PHN2ZyB2aWV3Qm94PScwIDAgMTUwIDE1MCcgeG1sbnM9J2h0dHA6Ly93d3cudzMub3JnLzIwMDAvc3ZnJz48L3N2Zz4=\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-src=\"https:\/\/thebiography.org\/wp-content\/uploads\/2021\/06\/10-Angelique-Boyer-Movies-and-TV-Shows-Rated-From-Best-To-Worst-1200x675-1-150x150.jpg\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/thebiography.org\/wp-content\/uploads\/2021\/06\/profile_pic.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"data:image\/svg+xml;base64,PHN2ZyB2aWV3Qm94PScwIDAgMTUwIDE1MCcgeG1sbnM9J2h0dHA6Ly93d3cudzMub3JnLzIwMDAvc3ZnJz48L3N2Zz4=\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" data-srcset=\"\/\/thebiography.org\/wp-content\/uploads\/2021\/06\/profile_pic-150x150.jpg 150w, \/\/thebiography.org\/wp-content\/uploads\/2021\/06\/profile_pic-300x300.jpg 300w, \/\/thebiography.org\/wp-content\/uploads\/2021\/06\/profile_pic-1024x1024.jpg 1024w, \/\/thebiography.org\/wp-content\/uploads\/2021\/06\/profile_pic-175x175.jpg 175w, \/\/thebiography.org\/wp-content\/uploads\/2021\/06\/profile_pic-450x450.jpg 450w, \/\/thebiography.org\/wp-content\/uploads\/2021\/06\/profile_pic-768x768.jpg 768w, \/\/thebiography.org\/wp-content\/uploads\/2021\/06\/profile_pic.jpg 1044w\" data-src=\"https:\/\/thebiography.org\/wp-content\/uploads\/2021\/06\/profile_pic-150x150.jpg\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\n<h2><span class=\"ez-toc-section\" id=\"Koerperliche_Eigenschaften_und_Hobbys\"><\/span>K\u00f6rperliche Eigenschaften und Hobbys<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Angelique ist 1,65 m gro\u00df und wiegt etwa 50 kg. Ihre K\u00f6rperma\u00dfe sind 94-61-86. Ihre nat\u00fcrliche Haarfarbe ist dunkelbraun, obwohl sie es den gr\u00f6\u00dften Teil ihres Lebens blond gef\u00e4rbt hat. Ihre Augen sind gr\u00fcn. Wenn sie nicht schauspielert oder modelt, filmt sie meist <a rel=\"nofollow\" href=\"https:\/\/bodysize.org\/en\/angelique-boyer\/\" target=\"_blank\">TikToks<\/a> oder trainiert. Bez\u00fcglich ihres Aussehens gab es Ger\u00fcchte, dass sie eine Nasenkorrektur (Nasen-OP) habe machen lassen, obwohl sie dies nie kommentiert oder Informationen dazu ver\u00f6ffentlicht hat.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Moechten_Sie_ihr_Vermoegen_wissen\"><\/span>M\u00f6chten Sie ihr Verm\u00f6gen wissen?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Ab 2021 wird Angeliques Verm\u00f6gen auf 6 Millionen Dollar gesch\u00e4tzt, die sie als Schauspielerin, Model und Mitbegr\u00fcnderin von Nuba verdient hat. Dar\u00fcber hinaus hat sie eine ziemlich gro\u00dfe Fangemeinde in den sozialen Medien, was ihr wahrscheinlich Werbevertr\u00e4ge einbringt.<\/p>\n<p><script async src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8220363953005131\" crossorigin=\"anonymous\"><\/script>\r\n<!-- TheBiography.org res4 -->\r\n<ins class=\"adsbygoogle\"\r\n     style=\"display:block\"\r\n     data-ad-client=\"ca-pub-8220363953005131\"\r\n     data-ad-slot=\"7189429181\"\r\n     data-ad-format=\"auto\"\r\n     data-full-width-responsive=\"true\"><\/ins>\r\n<script>\r\n     (adsbygoogle = window.adsbygoogle || []).push({});\r\n<\/script>\r\n<amp-ad layout=\"fixed-height\" height=300 type=\"adsense\" data-ad-client=\"ca-pub-8220363953005131\" data-ad-slot=\"7189429181\"><\/amp-ad>\r\n<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Skandale_und_Kontroversen\"><\/span>Skandale und Kontroversen<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Im Jahr 2017 soll Angelique zwei YouTuber namens Pepe und Teo angegriffen haben, die die ganze Situation auf ihrem Kanal schilderten. Die YouTuber entdeckten Angelique und ihren Freund beim Abendessen in einem Restaurant und sprachen das Paar an, um ein Foto zu machen. Als das Paar das Restaurant verlie\u00df, erschreckten Pepe und Teo sie und begannen, sie zu filmen, was ihnen nicht gefiel. Laut ihrem Bericht wurde Angelique aggressiv und fragte sie, ob sie im Restaurant <a rel=\"nofollow\" href=\"https:\/\/www.latintimes.com\/angelique-boyer-attacks-vlogger-sebastian-rulli-defends-telenovela-star-after-413968\" target=\"_blank\">arbeiteten<\/a>. Die YouTuber f\u00fchlten sich durch ihre Frage beleidigt, da sie dunkelh\u00e4utig waren, \u00e4hnlich wie die Mehrheit des dortigen Personals.<\/p>\n<p>https:\/\/www.instagram.com\/p\/CQMw00aA_B9\/<\/p>\n<p>Nachdem diese rassistische Anschuldigung viral ging, erkl\u00e4rte Angelique die Situation \u00fcber Twitter: \u201eEs tut mir leid wegen des Missverst\u00e4ndnisses, ich glaube nicht, dass ihr geh\u00f6rt habt, warum ich das gesagt habe, wir haben tats\u00e4chlich mit allen dort gearbeitet Fotos gemacht.\u201c Die YouTubers antworteten: \u201eVielen Dank, dass Sie sich an uns gewandt haben, f\u00fcr Ihre Entschuldigung und danke, dass Sie alles aufgekl\u00e4rt haben. Wir w\u00fcnschen Ihnen alles Gute.\u201c<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Ist_sie_in_den_sozialen_Medien_aktiv\"><\/span>Ist sie in den sozialen Medien aktiv?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Angelique ist auf verschiedenen Social-Media-Plattformen sehr aktiv. Ihr <a rel=\"nofollow\" href=\"https:\/\/www.instagram.com\/angeliqueboyer\/\" target=\"_blank\">Instagram<\/a> hat \u00fcber 13 Millionen Follower, w\u00e4hrend ihr Twitter \u00fcber 800.000 Follower z\u00e4hlt. Sie hat auch einen TikTok-Account, der \u00fcber sieben Millionen Follower und \u00fcber 24 Millionen Likes hat. Die vielseitige Schauspielerin hat auch auf Facebook eine betr\u00e4chtliche Fangemeinde aufgebaut, die derzeit bei etwa 11 Millionen liegt. Alle Fans, die an den neuesten Nachrichten und Projekten von Angelique interessiert sind, k\u00f6nnen ihre <a rel=\"nofollow\" href=\"https:\/\/teamangeliqueboyer.com\/noticias\/\" target=\"_blank\">Website<\/a> besuchen und auf dem Laufenden bleiben.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Wer ist Angelique Boyer? Angelique Boyer Rousseau \u00a0 ist Schauspielerin und Model, bekannt f\u00fcr ihre Auftritte in verschiedenen mexikanischen Telenovelas und Fernsehserien, darunter \u201eRebelde\u201c, \u201eAmar a Muerte\u201c und \u201eLo Que la Vida Robo\u201c. Sie wurde am 4. Juli 1988 im Zeichen Krebs in Saint-Claude Jura, Frankreich, geboren und hat mexikanische und franz\u00f6sische Vorfahren. Bis Mitte<\/p>\n","protected":false},"author":0,"featured_media":47590,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ep_exclude_from_search":false,"amp_status":"","footnotes":""},"categories":[6606,6579],"tags":[],"class_list":{"0":"post-70313","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-models-de","8":"category-schauspieler"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Angelique Boyers Biografie: Ehemann, Alter, Verm\u00f6gen, Familie<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/thebiography.org\/de\/angelique-boyers-biografie-ehemann-alter-vermogen-familie\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Angelique Boyers Biografie: Ehemann, Alter, Verm\u00f6gen, Familie\" \/>\n<meta property=\"og:description\" content=\"Wer ist Angelique Boyer? Angelique Boyer Rousseau \u00a0 ist Schauspielerin und Model, bekannt f\u00fcr ihre Auftritte in verschiedenen mexikanischen Telenovelas und Fernsehserien, darunter \u201eRebelde\u201c, \u201eAmar a Muerte\u201c und \u201eLo Que la Vida Robo\u201c. Sie wurde am 4. Juli 1988 im Zeichen Krebs in Saint-Claude Jura, Frankreich, geboren und hat mexikanische und franz\u00f6sische Vorfahren. Bis Mitte\" \/>\n<meta property=\"og:url\" content=\"https:\/\/thebiography.org\/de\/angelique-boyers-biografie-ehemann-alter-vermogen-familie\/\" \/>\n<meta property=\"og:site_name\" content=\"The Biography\" \/>\n<meta property=\"article:published_time\" content=\"2025-11-04T18:38:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/thebiography.org\/wp-content\/uploads\/2021\/06\/f8XO8AyetUDDNi1e-rmVrpeJlR8TSGso8Z7dO_fsERM.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1010\" \/>\n\t<meta property=\"og:image:height\" content=\"505\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"7\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/thebiography.org\/de\/angelique-boyers-biografie-ehemann-alter-vermogen-familie\/\",\"url\":\"https:\/\/thebiography.org\/de\/angelique-boyers-biografie-ehemann-alter-vermogen-familie\/\",\"name\":\"Angelique Boyers Biografie: Ehemann, Alter, Verm\u00f6gen, Familie\",\"isPartOf\":{\"@id\":\"https:\/\/thebiography.org\/de\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/thebiography.org\/de\/angelique-boyers-biografie-ehemann-alter-vermogen-familie\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/thebiography.org\/de\/angelique-boyers-biografie-ehemann-alter-vermogen-familie\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/thebiography.org\/wp-content\/uploads\/2021\/06\/f8XO8AyetUDDNi1e-rmVrpeJlR8TSGso8Z7dO_fsERM.jpg\",\"datePublished\":\"2025-11-04T18:38:48+00:00\",\"author\":{\"@id\":\"\"},\"breadcrumb\":{\"@id\":\"https:\/\/thebiography.org\/de\/angelique-boyers-biografie-ehemann-alter-vermogen-familie\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/thebiography.org\/de\/angelique-boyers-biografie-ehemann-alter-vermogen-familie\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/thebiography.org\/de\/angelique-boyers-biografie-ehemann-alter-vermogen-familie\/#primaryimage\",\"url\":\"https:\/\/thebiography.org\/wp-content\/uploads\/2021\/06\/f8XO8AyetUDDNi1e-rmVrpeJlR8TSGso8Z7dO_fsERM.jpg\",\"contentUrl\":\"https:\/\/thebiography.org\/wp-content\/uploads\/2021\/06\/f8XO8AyetUDDNi1e-rmVrpeJlR8TSGso8Z7dO_fsERM.jpg\",\"width\":1010,\"height\":505,\"caption\":\"Angelique Boyer\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/thebiography.org\/de\/angelique-boyers-biografie-ehemann-alter-vermogen-familie\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/thebiography.org\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Angelique Boyers Biografie: Ehemann, Alter, Verm\u00f6gen, Familie\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/thebiography.org\/de\/#website\",\"url\":\"https:\/\/thebiography.org\/de\/\",\"name\":\"The Biography\",\"description\":\"Relationships, Net Worth, Measurements\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/thebiography.org\/de\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Angelique Boyers Biografie: Ehemann, Alter, Verm\u00f6gen, Familie","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/thebiography.org\/de\/angelique-boyers-biografie-ehemann-alter-vermogen-familie\/","og_locale":"de_DE","og_type":"article","og_title":"Angelique Boyers Biografie: Ehemann, Alter, Verm\u00f6gen, Familie","og_description":"Wer ist Angelique Boyer? Angelique Boyer Rousseau \u00a0 ist Schauspielerin und Model, bekannt f\u00fcr ihre Auftritte in verschiedenen mexikanischen Telenovelas und Fernsehserien, darunter \u201eRebelde\u201c, \u201eAmar a Muerte\u201c und \u201eLo Que la Vida Robo\u201c. Sie wurde am 4. Juli 1988 im Zeichen Krebs in Saint-Claude Jura, Frankreich, geboren und hat mexikanische und franz\u00f6sische Vorfahren. Bis Mitte","og_url":"https:\/\/thebiography.org\/de\/angelique-boyers-biografie-ehemann-alter-vermogen-familie\/","og_site_name":"The Biography","article_published_time":"2025-11-04T18:38:48+00:00","og_image":[{"width":1010,"height":505,"url":"https:\/\/thebiography.org\/wp-content\/uploads\/2021\/06\/f8XO8AyetUDDNi1e-rmVrpeJlR8TSGso8Z7dO_fsERM.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"7\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/thebiography.org\/de\/angelique-boyers-biografie-ehemann-alter-vermogen-familie\/","url":"https:\/\/thebiography.org\/de\/angelique-boyers-biografie-ehemann-alter-vermogen-familie\/","name":"Angelique Boyers Biografie: Ehemann, Alter, Verm\u00f6gen, Familie","isPartOf":{"@id":"https:\/\/thebiography.org\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/thebiography.org\/de\/angelique-boyers-biografie-ehemann-alter-vermogen-familie\/#primaryimage"},"image":{"@id":"https:\/\/thebiography.org\/de\/angelique-boyers-biografie-ehemann-alter-vermogen-familie\/#primaryimage"},"thumbnailUrl":"https:\/\/thebiography.org\/wp-content\/uploads\/2021\/06\/f8XO8AyetUDDNi1e-rmVrpeJlR8TSGso8Z7dO_fsERM.jpg","datePublished":"2025-11-04T18:38:48+00:00","author":{"@id":""},"breadcrumb":{"@id":"https:\/\/thebiography.org\/de\/angelique-boyers-biografie-ehemann-alter-vermogen-familie\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/thebiography.org\/de\/angelique-boyers-biografie-ehemann-alter-vermogen-familie\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/thebiography.org\/de\/angelique-boyers-biografie-ehemann-alter-vermogen-familie\/#primaryimage","url":"https:\/\/thebiography.org\/wp-content\/uploads\/2021\/06\/f8XO8AyetUDDNi1e-rmVrpeJlR8TSGso8Z7dO_fsERM.jpg","contentUrl":"https:\/\/thebiography.org\/wp-content\/uploads\/2021\/06\/f8XO8AyetUDDNi1e-rmVrpeJlR8TSGso8Z7dO_fsERM.jpg","width":1010,"height":505,"caption":"Angelique Boyer"},{"@type":"BreadcrumbList","@id":"https:\/\/thebiography.org\/de\/angelique-boyers-biografie-ehemann-alter-vermogen-familie\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/thebiography.org\/de\/"},{"@type":"ListItem","position":2,"name":"Angelique Boyers Biografie: Ehemann, Alter, Verm\u00f6gen, Familie"}]},{"@type":"WebSite","@id":"https:\/\/thebiography.org\/de\/#website","url":"https:\/\/thebiography.org\/de\/","name":"The Biography","description":"Relationships, Net Worth, Measurements","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/thebiography.org\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"}]}},"_links":{"self":[{"href":"https:\/\/thebiography.org\/de\/wp-json\/wp\/v2\/posts\/70313","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/thebiography.org\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/thebiography.org\/de\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/thebiography.org\/de\/wp-json\/wp\/v2\/comments?post=70313"}],"version-history":[{"count":0,"href":"https:\/\/thebiography.org\/de\/wp-json\/wp\/v2\/posts\/70313\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/thebiography.org\/de\/wp-json\/wp\/v2\/media\/47590"}],"wp:attachment":[{"href":"https:\/\/thebiography.org\/de\/wp-json\/wp\/v2\/media?parent=70313"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/thebiography.org\/de\/wp-json\/wp\/v2\/categories?post=70313"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/thebiography.org\/de\/wp-json\/wp\/v2\/tags?post=70313"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}