{"id":73622,"date":"2025-12-01T11:59:52","date_gmt":"2025-12-01T11:59:52","guid":{"rendered":"http:\/\/localhost\/!projects\/!webs\/thebiography.org\/la-verite-cachee-sur-phill-lewis-accident-prison-fortune-nette-wiki\/"},"modified":"2025-09-06T21:15:27","modified_gmt":"2025-09-06T21:15:27","slug":"la-verite-cachee-sur-phill-lewis-accident-prison-fortune-nette-wiki","status":"publish","type":"post","link":"https:\/\/thebiography.org\/fr\/la-verite-cachee-sur-phill-lewis-accident-prison-fortune-nette-wiki\/","title":{"rendered":"La v\u00e9rit\u00e9 cach\u00e9e sur Phill Lewis : Accident, prison, fortune nette, wiki."},"content":{"rendered":"<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_77 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Table of Contents<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Toggle Table of Content\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 eztoc-toggle-hide-by-default' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/thebiography.org\/fr\/la-verite-cachee-sur-phill-lewis-accident-prison-fortune-nette-wiki\/#Qui_est_Phill_Lewis\" >Qui est Phill Lewis?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/thebiography.org\/fr\/la-verite-cachee-sur-phill-lewis-accident-prison-fortune-nette-wiki\/#Phill_Lewis_Wiki_Age_enfance_et_education\" >Phill Lewis Wiki: \u00c2ge, enfance et \u00e9ducation<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/thebiography.org\/fr\/la-verite-cachee-sur-phill-lewis-accident-prison-fortune-nette-wiki\/#Debuts_de_carriere_dacteur\" >D\u00e9buts de carri\u00e8re d&rsquo;acteur<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/thebiography.org\/fr\/la-verite-cachee-sur-phill-lewis-accident-prison-fortune-nette-wiki\/#Selever_en_puissance\" >S&rsquo;\u00e9lever en puissance<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/thebiography.org\/fr\/la-verite-cachee-sur-phill-lewis-accident-prison-fortune-nette-wiki\/#Carriere_de_comedien_de_voix\" >Carri\u00e8re de com\u00e9dien de voix<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/thebiography.org\/fr\/la-verite-cachee-sur-phill-lewis-accident-prison-fortune-nette-wiki\/#Realisateur_accompli\" >R\u00e9alisateur accompli<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https:\/\/thebiography.org\/fr\/la-verite-cachee-sur-phill-lewis-accident-prison-fortune-nette-wiki\/#Vie_personnelle_Accident_Prison_Femme_Enfants\" >Vie personnelle, Accident, Prison, Femme, Enfants<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-8\" href=\"https:\/\/thebiography.org\/fr\/la-verite-cachee-sur-phill-lewis-accident-prison-fortune-nette-wiki\/#Valeur_nette\" >Valeur nette<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-9\" href=\"https:\/\/thebiography.org\/fr\/la-verite-cachee-sur-phill-lewis-accident-prison-fortune-nette-wiki\/#Apparence_et_statistiques_vitales\" >Apparence et statistiques vitales<\/a><\/li><\/ul><\/nav><\/div>\n<h2><span class=\"ez-toc-section\" id=\"Qui_est_Phill_Lewis\"><\/span>Qui est Phill Lewis?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Phill Lewis est un acteur, acteur de voix, humoriste et r\u00e9alisateur am\u00e9ricain n\u00e9 en Ouganda, qui est encore probablement surtout connu dans le monde entier pour son r\u00f4le de M. Moseby dans la s\u00e9rie t\u00e9l\u00e9vis\u00e9e \u00ab\u00a0The Suite Life of Zack &#038; Cody\u00a0\u00bb (2005-2008), et son spin-off \u00ab\u00a0The Suite Life on Deck\u00a0\u00bb (2008-2011), en plus d&rsquo;un certain nombre d&rsquo;autres r\u00f4les qu&rsquo;il a obtenu jusqu&rsquo;\u00e0 pr\u00e9sent dans sa carri\u00e8re.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Phill_Lewis_Wiki_Age_enfance_et_education\"><\/span>Phill Lewis Wiki: \u00c2ge, enfance et \u00e9ducation<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Phillip David Lewis est n\u00e9 le 14 f\u00e9vrier 1968 sous le signe du Verseau \u00e0 Kampala, en Ouganda. Il est le fils de l&rsquo;ancien ambassadeur am\u00e9ricain Delano Lewis, qui \u00e9tait directeur associ\u00e9 et directeur pays du Corps de la Paix pour le Nigeria et l&rsquo;Ouganda, et de Gayle Carolyn Jones. Il a grandi aux \u00c9tats-Unis avec ses trois fr\u00e8res, Delano Jr., Geoffrey et Brian. Il n&rsquo;y a aucune information concernant son \u00e9ducation formelle.<\/p>\n<p>https:\/\/www.instagram.com\/p\/CLRW5zHnFMA\/<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Debuts_de_carriere_dacteur\"><\/span>D\u00e9buts de carri\u00e8re d&rsquo;acteur<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>La carri\u00e8re de Phill a commenc\u00e9 au milieu des ann\u00e9es 80 avec de petits r\u00f4les dans des s\u00e9ries t\u00e9l\u00e9vis\u00e9es telles que \u00ab Hill Street Blues \u00bb (1986) et \u00ab 227 \u00bb la m\u00eame ann\u00e9e. Il a poursuivi sa carri\u00e8re avec des r\u00f4les \u00e0 la t\u00e9l\u00e9vision, apparaissant dans des s\u00e9ries telles que \u00ab Frank\u2019s Place \u00bb et \u00ab The Bronx Zoo \u00bb, avant de faire ses d\u00e9buts au cin\u00e9ma en tant que Dennis dans le film de com\u00e9die polici\u00e8re \u00ab Heathers \u00bb. Il a termin\u00e9 la d\u00e9cennie avec un r\u00f4le dans le t\u00e9l\u00e9film \u00ab Protect and Surf \u00bb.<\/p>\n<p>Il a commenc\u00e9 les ann\u00e9es 90 avec des r\u00f4les mineurs dans des s\u00e9ries t\u00e9l\u00e9vis\u00e9es, puis en 1991, il est apparu dans plusieurs projets, en commen\u00e7ant par le r\u00f4le de Teech Gibson dans la s\u00e9rie t\u00e9l\u00e9vis\u00e9e \u00ab Teech \u00bb, puis en tant que Steve Jessup dans le film \u00ab City Slickers \u00bb, et \u00e9galement en tant que Charlie dans le t\u00e9l\u00e9film \u00ab Clippers \u00bb. Ensuite, il a \u00e9t\u00e9 Tee Vee dans le film \u00ab Aces: Iron Eagle III \u00bb en 1992, et deux ans plus tard, il a incarn\u00e9 Arnold Nixon dans la s\u00e9rie t\u00e9l\u00e9vis\u00e9e \u00ab Hardball \u00bb.<\/p>\n<p><script async src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8220363953005131\" crossorigin=\"anonymous\"><\/script>\r\n<!-- TheBiography.org res1 -->\r\n<ins class=\"adsbygoogle\"\r\n     style=\"display:block\"\r\n     data-ad-client=\"ca-pub-8220363953005131\"\r\n     data-ad-slot=\"3620885119\"\r\n     data-ad-format=\"auto\"\r\n     data-full-width-responsive=\"true\"><\/ins>\r\n<script>\r\n     (adsbygoogle = window.adsbygoogle || []).push({});\r\n<\/script>\r\n<amp-ad layout=\"fixed-height\" height=300 type=\"adsense\" data-ad-client=\"ca-pub-8220363953005131\" data-ad-slot=\"3620885119\"><\/amp-ad>\r\n<\/p>\n<p>En 1995, il a \u00e9t\u00e9 choisi pour le r\u00f4le de T.C. dans la s\u00e9rie comique t\u00e9l\u00e9vis\u00e9e \u00ab The Wayans Bros. \u00bb, avec Shawn et Marlon Wayans, et a termin\u00e9 la d\u00e9cennie avec un r\u00f4le important dans le film dramatique \u00ab $pent \u00bb, avec Jason London et Charlie Spradling.<\/p>\n<p>De 2001 \u00e0 2006, il a jou\u00e9 Roy dans la s\u00e9rie comique t\u00e9l\u00e9vis\u00e9e \u00ab Yes, Dear \u00bb, apparaissant dans 10 \u00e9pisodes de la s\u00e9rie nomin\u00e9e aux Primetime Emmy Awards, et a \u00e9galement jou\u00e9 dans plusieurs films, dont la com\u00e9die romantique \u00ab The Third Wheel \u00bb (2001) et le film d&rsquo;action et de com\u00e9die \u00ab I Spy \u00bb (2002), avec Eddie Murphy et Owen Wilson. En 2004, il a \u00e9t\u00e9 Charlie dans le film \u00ab Elvis Has Left the Building \u00bb, et a \u00e9galement eu un r\u00f4le dans le film \u00ab Surviving Christmas \u00bb.<\/p>\n<p><iframe title=\"First driving lesson\" width=\"770\" height=\"578\" src=\"https:\/\/www.youtube.com\/embed\/8hsWnvwIJWA?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n<h2><span class=\"ez-toc-section\" id=\"Selever_en_puissance\"><\/span>S&rsquo;\u00e9lever en puissance<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>En 2005, Phill a \u00e9t\u00e9 choisi pour l&rsquo;un de ses r\u00f4les les plus importants, celui de M. Moseby dans la s\u00e9rie t\u00e9l\u00e9vis\u00e9e \u00ab\u00a0La Vie de Zack et Cody\u00a0\u00bb, apparaissant dans les 87 \u00e9pisodes de la s\u00e9rie comique prim\u00e9e, ce qui l&rsquo;a rendu tr\u00e8s populaire. Il a repris le r\u00f4le dans le spin-off \u00ab\u00a0La Vie de croisi\u00e8re de Zack et Cody\u00a0\u00bb (2008-2011), augmentant encore sa popularit\u00e9, et a continu\u00e9 d&rsquo;incarner M. Moseby dans plusieurs s\u00e9ries de Disney Channel, notamment \u00ab\u00a0Les Sorciers de Waverly Place\u00a0\u00bb, \u00ab\u00a0Hannah Montana\u00a0\u00bb et d&rsquo;autres en tant qu&rsquo;invit\u00e9.<\/p>\n<p>De plus, Phill a jou\u00e9 dans la s\u00e9rie comique-dramatique \u00ab Pretty Ugly People \u00bb, et en 2012, il \u00e9tait Rick Street dans le film comique \u00ab Like Father \u00bb, \u00e9crit et r\u00e9alis\u00e9 par Bill Lawrence.<\/p>\n<p><script async src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8220363953005131\" crossorigin=\"anonymous\"><\/script>\r\n<!-- TheBiography.org res2 -->\r\n<ins class=\"adsbygoogle\"\r\n     style=\"display:block\"\r\n     data-ad-client=\"ca-pub-8220363953005131\"\r\n     data-ad-slot=\"8502510853\"\r\n     data-ad-format=\"auto\"\r\n     data-full-width-responsive=\"true\"><\/ins>\r\n<script>\r\n     (adsbygoogle = window.adsbygoogle || []).push({});\r\n<\/script>\r\n<amp-ad layout=\"fixed-height\" height=300 type=\"adsense\" data-ad-client=\"ca-pub-8220363953005131\" data-ad-slot=\"8502510853\"><\/amp-ad>\r\n<\/p>\n<p>Depuis lors, Phill s&rsquo;est davantage concentr\u00e9 sur des r\u00f4les de voix et d&rsquo;autres int\u00e9r\u00eats, et a fait peu d&rsquo;apparitions \u00e0 l&rsquo;\u00e9cran \u2013 sa derni\u00e8re apparition \u00e0 l&rsquo;\u00e9cran remonte \u00e0 2016, o\u00f9 il interpr\u00e9tait Walt dans la s\u00e9rie t\u00e9l\u00e9vis\u00e9e \u00ab Angel from Hell \u00bb.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Carriere_de_comedien_de_voix\"><\/span>Carri\u00e8re de com\u00e9dien de voix<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Phill est \u00e9galement acteur de voix, faisant ses d\u00e9buts en 2000 en tant que voix du capitaine James Lawrence dans la s\u00e9rie anim\u00e9e \u00ab Histeria! \u00bb. Ensuite, il a \u00e9t\u00e9 choisi pour donner sa voix \u00e0 Duper dans la s\u00e9rie anim\u00e9e tr\u00e8s acclam\u00e9e \u00ab American Dad! \u00bb, o\u00f9 il a interpr\u00e9t\u00e9 le personnage dans six \u00e9pisodes de 2005 \u00e0 2020. En 2007, il a doubl\u00e9 Coco Banana dans la s\u00e9rie anim\u00e9e \u00ab Kim Possible \u00bb et a \u00e9galement commenc\u00e9 \u00e0 donner sa voix \u00e0 DJay dans la s\u00e9rie anim\u00e9e d\u2019action et de com\u00e9die \u00ab Total Drama \u00bb.<\/p>\n<figure id=\"attachment_19892\" aria-describedby=\"caption-attachment-19892\" style=\"width: 683px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-19892\" src=\"https:\/\/thebiography.org\/wp-content\/uploads\/2021\/07\/Phill-Lewis-Guest-Starred-on-Sister-Sister-683x1024.jpg\" alt=\"\" width=\"683\" height=\"1024\" srcset=\"\/\/thebiography.org\/wp-content\/uploads\/2021\/07\/Phill-Lewis-Guest-Starred-on-Sister-Sister-683x1024.jpg 683w, \/\/thebiography.org\/wp-content\/uploads\/2021\/07\/Phill-Lewis-Guest-Starred-on-Sister-Sister-200x300.jpg 200w, \/\/thebiography.org\/wp-content\/uploads\/2021\/07\/Phill-Lewis-Guest-Starred-on-Sister-Sister-1024x1536.jpg 1024w, \/\/thebiography.org\/wp-content\/uploads\/2021\/07\/Phill-Lewis-Guest-Starred-on-Sister-Sister-1365x2048.jpg 1365w, \/\/thebiography.org\/wp-content\/uploads\/2021\/07\/Phill-Lewis-Guest-Starred-on-Sister-Sister-175x263.jpg 175w, \/\/thebiography.org\/wp-content\/uploads\/2021\/07\/Phill-Lewis-Guest-Starred-on-Sister-Sister-450x675.jpg 450w, \/\/thebiography.org\/wp-content\/uploads\/2021\/07\/Phill-Lewis-Guest-Starred-on-Sister-Sister-1170x1755.jpg 1170w, \/\/thebiography.org\/wp-content\/uploads\/2021\/07\/Phill-Lewis-Guest-Starred-on-Sister-Sister-768x1152.jpg 768w, \/\/thebiography.org\/wp-content\/uploads\/2021\/07\/Phill-Lewis-Guest-Starred-on-Sister-Sister-scaled.jpg 1707w\" sizes=\"auto, (max-width: 683px) 100vw, 683px\" \/><figcaption id=\"caption-attachment-19892\" class=\"wp-caption-text\"><a href=\"https:\/\/media1.popsugar-assets.com\/files\/thumbor\/nIhq2fmByG0w8w0rL2hzqNzXHuc\/fit-in\/2048xorig\/filters:format_auto-!-:strip_icc-!-\/2020\/09\/02\/892\/n\/1922283\/3e09775939d5eac7_GettyImages-81512608\/i\/Phill-Lewis-Guest-Starred-on-Sister-Sister.jpg\" target=\"_blank\" rel=\"nofollow noopener\">Phill Lewis<\/a><\/figcaption><\/figure>\n<p>En 2009, il a commenc\u00e9 \u00e0 doubler l&rsquo;agent sp\u00e9cial Wolfie dans la s\u00e9rie anim\u00e9e \u00ab Special Agent Oso \u00bb (2009-2012), et en 2020, il a doubl\u00e9 Reginald dans la s\u00e9rie d&rsquo;action et de com\u00e9die \u00ab The Healing Powers of Dude \u00bb.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Realisateur_accompli\"><\/span>R\u00e9alisateur accompli<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Phill Lewis est \u00e9galement r\u00e9alisateur; il a fait ses d\u00e9buts de r\u00e9alisateur avec un \u00e9pisode de \u00ab La Vie de Zack et Cody \u00bb en 2007, puis de 2008 \u00e0 2011, il a r\u00e9alis\u00e9 neuf \u00e9pisodes de la s\u00e9rie d\u00e9riv\u00e9e \u00ab La Vie sur le pont \u00bb. En 2011, il a r\u00e9alis\u00e9 un \u00e9pisode de la s\u00e9rie t\u00e9l\u00e9vis\u00e9e \u00ab Jessie \u00bb, et jusqu&rsquo;en 2015, il en a r\u00e9alis\u00e9 huit autres. Son prochain projet a \u00e9t\u00e9 \u00ab Bonne chance Charlie \u00bb, dont il a r\u00e9alis\u00e9 sept \u00e9pisodes de 2011 \u00e0 2013, tandis que de 2012 \u00e0 2014, il a travaill\u00e9 sur la s\u00e9rie t\u00e9l\u00e9vis\u00e9e \u00ab Mike &amp; Molly \u00bb.<\/p>\n<p><script async src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8220363953005131\" crossorigin=\"anonymous\"><\/script>\r\n<!-- TheBiography.org res3 -->\r\n<ins class=\"adsbygoogle\"\r\n     style=\"display:block\"\r\n     data-ad-client=\"ca-pub-8220363953005131\"\r\n     data-ad-slot=\"1812684276\"\r\n     data-ad-format=\"auto\"\r\n     data-full-width-responsive=\"true\"><\/ins>\r\n<script>\r\n     (adsbygoogle = window.adsbygoogle || []).push({});\r\n<\/script>\r\n<amp-ad layout=\"fixed-height\" height=300 type=\"adsense\" data-ad-client=\"ca-pub-8220363953005131\" data-ad-slot=\"1812684276\"><\/amp-ad>\r\n<\/p>\n<p>Ensuite, il a r\u00e9alis\u00e9 11 \u00e9pisodes de la populaire s\u00e9rie t\u00e9l\u00e9vis\u00e9e comique \u201c2 Broke Girls\u201d (2013-2014), et en 2015, il a travaill\u00e9 sur la s\u00e9rie t\u00e9l\u00e9vis\u00e9e \u201cRichie Rich\u201d. Il a continu\u00e9 \u00e0 travailler sur un certain nombre de s\u00e9ries t\u00e9l\u00e9vis\u00e9es, dont \u201cThe Odd Couple\u201d (2015-2017), \u201cDr. Ken\u201d (2016-2017), \u201cOne Day at a Time\u201d (2017-2020), et plusieurs autres. Plus r\u00e9cemment, en 2021, il a r\u00e9alis\u00e9 deux \u00e9pisodes de la populaire s\u00e9rie t\u00e9l\u00e9vis\u00e9e \u201ciCarly\u201d.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Vie_personnelle_Accident_Prison_Femme_Enfants\"><\/span>Vie personnelle, Accident, Prison, Femme, Enfants<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Phill a \u00e9t\u00e9 impliqu\u00e9 dans un accident de voiture en d\u00e9cembre 1991, au cours duquel Isabel Duarte a perdu la vie. Phill \u00e9tait au volant et a \u00e9t\u00e9 accus\u00e9 d&rsquo;homicide involontaire et de conduite en \u00e9tat d&rsquo;ivresse, son taux d&rsquo;alcool\u00e9mie \u00e9tant trois fois sup\u00e9rieur \u00e0 la limite l\u00e9gale.<\/p>\n<div id='gallery-2' class='gallery galleryid-73622 gallery-columns-4 gallery-size-thumbnail'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/thebiography.org\/wp-content\/uploads\/2021\/07\/1200px-Phill_Lewis.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"data:image\/svg+xml;base64,PHN2ZyB2aWV3Qm94PScwIDAgMTUwIDE1MCcgeG1sbnM9J2h0dHA6Ly93d3cudzMub3JnLzIwMDAvc3ZnJz48L3N2Zz4=\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-src=\"https:\/\/thebiography.org\/wp-content\/uploads\/2021\/07\/1200px-Phill_Lewis-150x150.jpg\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/thebiography.org\/wp-content\/uploads\/2021\/07\/cole-dylan-sprouse-reunite-phill-lewis-nyc-02.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"data:image\/svg+xml;base64,PHN2ZyB2aWV3Qm94PScwIDAgMTUwIDE1MCcgeG1sbnM9J2h0dHA6Ly93d3cudzMub3JnLzIwMDAvc3ZnJz48L3N2Zz4=\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-src=\"https:\/\/thebiography.org\/wp-content\/uploads\/2021\/07\/cole-dylan-sprouse-reunite-phill-lewis-nyc-02-150x150.jpg\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/thebiography.org\/wp-content\/uploads\/2021\/07\/why-did-phill-lewis-get-arrested-1-1575583482350.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"data:image\/svg+xml;base64,PHN2ZyB2aWV3Qm94PScwIDAgMTUwIDE1MCcgeG1sbnM9J2h0dHA6Ly93d3cudzMub3JnLzIwMDAvc3ZnJz48L3N2Zz4=\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-src=\"https:\/\/thebiography.org\/wp-content\/uploads\/2021\/07\/why-did-phill-lewis-get-arrested-1-1575583482350-150x150.jpg\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/thebiography.org\/wp-content\/uploads\/2021\/07\/sub-buzz-20384-1502462954-3.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"data:image\/svg+xml;base64,PHN2ZyB2aWV3Qm94PScwIDAgMTUwIDE1MCcgeG1sbnM9J2h0dHA6Ly93d3cudzMub3JnLzIwMDAvc3ZnJz48L3N2Zz4=\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-src=\"https:\/\/thebiography.org\/wp-content\/uploads\/2021\/07\/sub-buzz-20384-1502462954-3-150x150.jpg\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\n<p>Il a \u00e9t\u00e9 condamn\u00e9 \u00e0 cinq ans de prison, dont quatre avec sursis, car apr\u00e8s son arrestation, Phill a collabor\u00e9 avec une troupe de th\u00e9\u00e2tre bas\u00e9e en prison, se produisant dans des prisons, des \u00e9coles et des \u00e9glises, et sensibilisant \u00e9galement aux cons\u00e9quences de la toxicomanie et de l\u2019alcoolisme. Par cons\u00e9quent, il a \u00e9t\u00e9 plac\u00e9 en libert\u00e9 conditionnelle pendant deux ans apr\u00e8s sa lib\u00e9ration, et a \u00e9t\u00e9 condamn\u00e9 \u00e0 effectuer 350 heures de travaux d\u2019int\u00e9r\u00eat g\u00e9n\u00e9ral.<\/p>\n<p>Phill est un homme mari\u00e9; sa femme est Megan Benton Lewis, et bien qu&rsquo;il n&rsquo;y ait aucune information sur la date de leur mariage, ils ont deux enfants, des filles nomm\u00e9es Piper et Annie Lewis.<\/p>\n<p><script async src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8220363953005131\" crossorigin=\"anonymous\"><\/script>\r\n<!-- TheBiography.org res4 -->\r\n<ins class=\"adsbygoogle\"\r\n     style=\"display:block\"\r\n     data-ad-client=\"ca-pub-8220363953005131\"\r\n     data-ad-slot=\"7189429181\"\r\n     data-ad-format=\"auto\"\r\n     data-full-width-responsive=\"true\"><\/ins>\r\n<script>\r\n     (adsbygoogle = window.adsbygoogle || []).push({});\r\n<\/script>\r\n<amp-ad layout=\"fixed-height\" height=300 type=\"adsense\" data-ad-client=\"ca-pub-8220363953005131\" data-ad-slot=\"7189429181\"><\/amp-ad>\r\n<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Valeur_nette\"><\/span>Valeur nette<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>\u00c0 mi-2021, la fortune nette de Phill Lewis a \u00e9t\u00e9 estim\u00e9e \u00e0 environ 1,5 million de dollars, gagn\u00e9s gr\u00e2ce \u00e0 sa carri\u00e8re r\u00e9ussie d&rsquo;acteur et de r\u00e9alisateur. En tant qu&rsquo;acteur, il est apparu dans 100 titres de films et de t\u00e9l\u00e9vision, tandis qu&rsquo;en tant que r\u00e9alisateur, il compte 55 cr\u00e9dits t\u00e9l\u00e9visuels.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Apparence_et_statistiques_vitales\"><\/span>Apparence et statistiques vitales<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Cet acteur et r\u00e9alisateur \u00e0 succ\u00e8s a les cheveux noirs et les yeux marron. Il mesure 1m60 (5ft 6ins), tandis que son poids et d&rsquo;autres informations vitales sont actuellement inconnus, bien qu&rsquo;il ait une carrure moyenne.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Qui est Phill Lewis? Phill Lewis est un acteur, acteur de voix, humoriste et r\u00e9alisateur am\u00e9ricain n\u00e9 en Ouganda, qui est encore probablement surtout connu dans le monde entier pour son r\u00f4le de M. Moseby dans la s\u00e9rie t\u00e9l\u00e9vis\u00e9e \u00ab\u00a0The Suite Life of Zack &#038; Cody\u00a0\u00bb (2005-2008), et son spin-off \u00ab\u00a0The Suite Life on Deck\u00a0\u00bb<\/p>\n","protected":false},"author":1,"featured_media":19891,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ep_exclude_from_search":false,"amp_status":"","footnotes":""},"categories":[6580,6592,6597],"tags":[],"class_list":{"0":"post-73622","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-acteurs","8":"category-comediens","9":"category-realisateurs"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>La v\u00e9rit\u00e9 cach\u00e9e sur Phill Lewis : Accident, prison, fortune nette, wiki.<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/thebiography.org\/fr\/la-verite-cachee-sur-phill-lewis-accident-prison-fortune-nette-wiki\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La v\u00e9rit\u00e9 cach\u00e9e sur Phill Lewis : Accident, prison, fortune nette, wiki.\" \/>\n<meta property=\"og:description\" content=\"Qui est Phill Lewis? Phill Lewis est un acteur, acteur de voix, humoriste et r\u00e9alisateur am\u00e9ricain n\u00e9 en Ouganda, qui est encore probablement surtout connu dans le monde entier pour son r\u00f4le de M. Moseby dans la s\u00e9rie t\u00e9l\u00e9vis\u00e9e \u00ab\u00a0The Suite Life of Zack &#038; Cody\u00a0\u00bb (2005-2008), et son spin-off \u00ab\u00a0The Suite Life on Deck\u00a0\u00bb\" \/>\n<meta property=\"og:url\" content=\"https:\/\/thebiography.org\/fr\/la-verite-cachee-sur-phill-lewis-accident-prison-fortune-nette-wiki\/\" \/>\n<meta property=\"og:site_name\" content=\"The Biography\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/daniel.wanburg\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-12-01T11:59:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/thebiography.org\/wp-content\/uploads\/2021\/07\/gettyimages-671708154-1024x1024-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1001\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Daniel Wanburg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Daniel Wanburg\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/thebiography.org\/fr\/la-verite-cachee-sur-phill-lewis-accident-prison-fortune-nette-wiki\/\",\"url\":\"https:\/\/thebiography.org\/fr\/la-verite-cachee-sur-phill-lewis-accident-prison-fortune-nette-wiki\/\",\"name\":\"La v\u00e9rit\u00e9 cach\u00e9e sur Phill Lewis : Accident, prison, fortune nette, wiki.\",\"isPartOf\":{\"@id\":\"https:\/\/thebiography.org\/fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/thebiography.org\/fr\/la-verite-cachee-sur-phill-lewis-accident-prison-fortune-nette-wiki\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/thebiography.org\/fr\/la-verite-cachee-sur-phill-lewis-accident-prison-fortune-nette-wiki\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/thebiography.org\/wp-content\/uploads\/2021\/07\/gettyimages-671708154-1024x1024-1.jpg\",\"datePublished\":\"2025-12-01T11:59:52+00:00\",\"author\":{\"@id\":\"https:\/\/thebiography.org\/fr\/#\/schema\/person\/1d126e3e6e3c48b3ff869d116a4fbc1c\"},\"breadcrumb\":{\"@id\":\"https:\/\/thebiography.org\/fr\/la-verite-cachee-sur-phill-lewis-accident-prison-fortune-nette-wiki\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/thebiography.org\/fr\/la-verite-cachee-sur-phill-lewis-accident-prison-fortune-nette-wiki\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/thebiography.org\/fr\/la-verite-cachee-sur-phill-lewis-accident-prison-fortune-nette-wiki\/#primaryimage\",\"url\":\"https:\/\/thebiography.org\/wp-content\/uploads\/2021\/07\/gettyimages-671708154-1024x1024-1.jpg\",\"contentUrl\":\"https:\/\/thebiography.org\/wp-content\/uploads\/2021\/07\/gettyimages-671708154-1024x1024-1.jpg\",\"width\":1001,\"height\":500,\"caption\":\"Phill Lewis\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/thebiography.org\/fr\/la-verite-cachee-sur-phill-lewis-accident-prison-fortune-nette-wiki\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/thebiography.org\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La v\u00e9rit\u00e9 cach\u00e9e sur Phill Lewis : Accident, prison, fortune nette, wiki.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/thebiography.org\/fr\/#website\",\"url\":\"https:\/\/thebiography.org\/fr\/\",\"name\":\"The Biography\",\"description\":\"Relationships, Net Worth, Measurements\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/thebiography.org\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/thebiography.org\/fr\/#\/schema\/person\/1d126e3e6e3c48b3ff869d116a4fbc1c\",\"name\":\"Daniel Wanburg\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/thebiography.org\/fr\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/ea3e6e37b405aa3457baa18b3ae51ab5564d43737a0427463d5d20892d4d11b9?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/ea3e6e37b405aa3457baa18b3ae51ab5564d43737a0427463d5d20892d4d11b9?s=96&d=mm&r=g\",\"caption\":\"Daniel Wanburg\"},\"description\":\"As Managing Editor at The Biography, I oversee a skilled team to produce insightful biographies of influential figures. My responsibilities include managing the editorial process, conducting detailed research, crafting engaging narratives, and ensuring the accuracy and quality of our content. At The Biography, we aim to deliver in-depth profiles that provide valuable insights into the realms of business, entertainment, and more. Our commitment to meticulous research and dynamic storytelling highlights the significant journeys and successes of inspiring individuals.\",\"sameAs\":[\"https:\/\/www.facebook.com\/daniel.wanburg\/\",\"https:\/\/www.linkedin.com\/in\/daniel-wanburg-618177164\/\"],\"url\":\"https:\/\/thebiography.org\/fr\/author\/admin\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La v\u00e9rit\u00e9 cach\u00e9e sur Phill Lewis : Accident, prison, fortune nette, wiki.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/thebiography.org\/fr\/la-verite-cachee-sur-phill-lewis-accident-prison-fortune-nette-wiki\/","og_locale":"fr_FR","og_type":"article","og_title":"La v\u00e9rit\u00e9 cach\u00e9e sur Phill Lewis : Accident, prison, fortune nette, wiki.","og_description":"Qui est Phill Lewis? Phill Lewis est un acteur, acteur de voix, humoriste et r\u00e9alisateur am\u00e9ricain n\u00e9 en Ouganda, qui est encore probablement surtout connu dans le monde entier pour son r\u00f4le de M. Moseby dans la s\u00e9rie t\u00e9l\u00e9vis\u00e9e \u00ab\u00a0The Suite Life of Zack &#038; Cody\u00a0\u00bb (2005-2008), et son spin-off \u00ab\u00a0The Suite Life on Deck\u00a0\u00bb","og_url":"https:\/\/thebiography.org\/fr\/la-verite-cachee-sur-phill-lewis-accident-prison-fortune-nette-wiki\/","og_site_name":"The Biography","article_author":"https:\/\/www.facebook.com\/daniel.wanburg\/","article_published_time":"2025-12-01T11:59:52+00:00","og_image":[{"width":1001,"height":500,"url":"https:\/\/thebiography.org\/wp-content\/uploads\/2021\/07\/gettyimages-671708154-1024x1024-1.jpg","type":"image\/jpeg"}],"author":"Daniel Wanburg","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Daniel Wanburg","Dur\u00e9e de lecture estim\u00e9e":"7 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/thebiography.org\/fr\/la-verite-cachee-sur-phill-lewis-accident-prison-fortune-nette-wiki\/","url":"https:\/\/thebiography.org\/fr\/la-verite-cachee-sur-phill-lewis-accident-prison-fortune-nette-wiki\/","name":"La v\u00e9rit\u00e9 cach\u00e9e sur Phill Lewis : Accident, prison, fortune nette, wiki.","isPartOf":{"@id":"https:\/\/thebiography.org\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/thebiography.org\/fr\/la-verite-cachee-sur-phill-lewis-accident-prison-fortune-nette-wiki\/#primaryimage"},"image":{"@id":"https:\/\/thebiography.org\/fr\/la-verite-cachee-sur-phill-lewis-accident-prison-fortune-nette-wiki\/#primaryimage"},"thumbnailUrl":"https:\/\/thebiography.org\/wp-content\/uploads\/2021\/07\/gettyimages-671708154-1024x1024-1.jpg","datePublished":"2025-12-01T11:59:52+00:00","author":{"@id":"https:\/\/thebiography.org\/fr\/#\/schema\/person\/1d126e3e6e3c48b3ff869d116a4fbc1c"},"breadcrumb":{"@id":"https:\/\/thebiography.org\/fr\/la-verite-cachee-sur-phill-lewis-accident-prison-fortune-nette-wiki\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/thebiography.org\/fr\/la-verite-cachee-sur-phill-lewis-accident-prison-fortune-nette-wiki\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/thebiography.org\/fr\/la-verite-cachee-sur-phill-lewis-accident-prison-fortune-nette-wiki\/#primaryimage","url":"https:\/\/thebiography.org\/wp-content\/uploads\/2021\/07\/gettyimages-671708154-1024x1024-1.jpg","contentUrl":"https:\/\/thebiography.org\/wp-content\/uploads\/2021\/07\/gettyimages-671708154-1024x1024-1.jpg","width":1001,"height":500,"caption":"Phill Lewis"},{"@type":"BreadcrumbList","@id":"https:\/\/thebiography.org\/fr\/la-verite-cachee-sur-phill-lewis-accident-prison-fortune-nette-wiki\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/thebiography.org\/fr\/"},{"@type":"ListItem","position":2,"name":"La v\u00e9rit\u00e9 cach\u00e9e sur Phill Lewis : Accident, prison, fortune nette, wiki."}]},{"@type":"WebSite","@id":"https:\/\/thebiography.org\/fr\/#website","url":"https:\/\/thebiography.org\/fr\/","name":"The Biography","description":"Relationships, Net Worth, Measurements","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/thebiography.org\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/thebiography.org\/fr\/#\/schema\/person\/1d126e3e6e3c48b3ff869d116a4fbc1c","name":"Daniel Wanburg","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/thebiography.org\/fr\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/ea3e6e37b405aa3457baa18b3ae51ab5564d43737a0427463d5d20892d4d11b9?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ea3e6e37b405aa3457baa18b3ae51ab5564d43737a0427463d5d20892d4d11b9?s=96&d=mm&r=g","caption":"Daniel Wanburg"},"description":"As Managing Editor at The Biography, I oversee a skilled team to produce insightful biographies of influential figures. My responsibilities include managing the editorial process, conducting detailed research, crafting engaging narratives, and ensuring the accuracy and quality of our content. At The Biography, we aim to deliver in-depth profiles that provide valuable insights into the realms of business, entertainment, and more. Our commitment to meticulous research and dynamic storytelling highlights the significant journeys and successes of inspiring individuals.","sameAs":["https:\/\/www.facebook.com\/daniel.wanburg\/","https:\/\/www.linkedin.com\/in\/daniel-wanburg-618177164\/"],"url":"https:\/\/thebiography.org\/fr\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/thebiography.org\/fr\/wp-json\/wp\/v2\/posts\/73622","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/thebiography.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/thebiography.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/thebiography.org\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/thebiography.org\/fr\/wp-json\/wp\/v2\/comments?post=73622"}],"version-history":[{"count":0,"href":"https:\/\/thebiography.org\/fr\/wp-json\/wp\/v2\/posts\/73622\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/thebiography.org\/fr\/wp-json\/wp\/v2\/media\/19891"}],"wp:attachment":[{"href":"https:\/\/thebiography.org\/fr\/wp-json\/wp\/v2\/media?parent=73622"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/thebiography.org\/fr\/wp-json\/wp\/v2\/categories?post=73622"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/thebiography.org\/fr\/wp-json\/wp\/v2\/tags?post=73622"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}