{"id":75590,"date":"2025-09-11T05:47:02","date_gmt":"2025-09-11T05:47:02","guid":{"rendered":"http:\/\/localhost\/!projects\/!webs\/thebiography.org\/fatti-che-non-sapevi-sugli-impractical-jokers\/"},"modified":"2025-09-11T05:47:02","modified_gmt":"2025-09-11T05:47:02","slug":"fatti-che-non-sapevi-sugli-impractical-jokers","status":"publish","type":"post","link":"https:\/\/thebiography.org\/it\/fatti-che-non-sapevi-sugli-impractical-jokers\/","title":{"rendered":"Fatti che non sapevi sugli Impractical Jokers"},"content":{"rendered":"<p>Fatti che non sapevi sugli Impractical JokersMolti considererebbero la risata universale, e potrebbero non avere torto, soprattutto considerando la popolarit\u00e0 di alcuni programmi comici e dei video virali su internet. Naturalmente, non c&#8217;\u00e8 modo migliore per godersi il tempo libero che ridere di qualcosa che vale una risata. Sapendo questo, NorthSouth Productions ha creato la loro serie reality sempre popolare, \u2018Impractical Jokers\u2019, e da quando \u00e8 stata presentata nel 2011, ha intrattenuto milioni di persone in tutto il mondo.<\/p>\n<p>Lo show segue gli scherzi e le divertenti imprese di quattro amici, rispettivamente conosciuti come The Tenderloins e composti da James Murray, Joe Gatto, Sal Vulcano e Brian Quinn. Un episodio tipico presenta una serie di sfide competitive o giochi in cui ogni burlone deve competere. Valutati in base alla loro performance, ricevono commenti positivi o negativi. Chiunque non riesca a completare una sfida o perda la competizione riceve una punizione alla fine di ogni episodio, solitamente sotto forma di uno scherzo audace.<\/p>\n<p>https:\/\/www.instagram.com\/p\/CE9x00MADYN\/<\/p>\n<p>Per loro natura, i giochi e gli scherzi mettono il partecipante burlone in una situazione imbarazzante, generalmente coinvolgendo membri del pubblico ignari. Gli altri burloni forniscono quindi istruzioni impossibili da dietro telecamere nascoste, ovviamente, sperando che il loro concorrente fallisca. Mentre ci\u00f2 accade, telecamere nascoste da diverse angolazioni catturano ogni momento esilarante in filmato, dalle reazioni della folla ai momenti sudati e stressanti che ogni burlone sperimenta. Le sfide subiscono poca struttura e pianificazione preventiva, facendo affidamento principalmente sull&#8217;improvvisazione per il loro successo.<\/p>\n<p>La punizione per il perdente alla fine di ogni episodio, tuttavia, sembra quasi sadicamente pianificata molto prima dell&#8217;inizio delle riprese. Di conseguenza, non dovrebbe sorprendere che l&#8217;introduzione del programma metta in guardia gli spettatori sulla stupidit\u00e0 esplicita tra quattro amici di lunga data. Grazie al successo universale di \u2018Impractical Jokers\u2019, lo show ha facilmente raggiunto la sua nona stagione e, a febbraio 2021, ha ricevuto il via libera per una decima stagione.<\/p>\n<p><script async src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8220363953005131\" crossorigin=\"anonymous\"><\/script>\r\n<!-- TheBiography.org res1 -->\r\n<ins class=\"adsbygoogle\"\r\n     style=\"display:block\"\r\n     data-ad-client=\"ca-pub-8220363953005131\"\r\n     data-ad-slot=\"3620885119\"\r\n     data-ad-format=\"auto\"\r\n     data-full-width-responsive=\"true\"><\/ins>\r\n<script>\r\n     (adsbygoogle = window.adsbygoogle || []).push({});\r\n<\/script>\r\n<amp-ad layout=\"fixed-height\" height=300 type=\"adsense\" data-ad-client=\"ca-pub-8220363953005131\" data-ad-slot=\"3620885119\"><\/amp-ad>\r\n<\/p>\n<p>Nel febbraio 2020, lo show ha rilasciato anche un lungometraggio molto atteso, e la sua popolarit\u00e0 ha portato alla creazione di numerosi spin-off. Tuttavia, anche un programma leggero come \u2018Impractical Jokers\u2019 potrebbe nascondere alcuni oscuri segreti, e tra tutte le risate, alcuni dettagli sfuggono facilmente agli spettatori a casa.<\/p>\n<p>Per i fan l\u00e0 fuori che potrebbero pensare di sapere tutto di \u2018Impractical Jokers\u2019, o dei Tenderloins, potrebbero esserci alcune sorprese ad attenderli. Speriamo, per\u00f2, che ci\u00f2 non cambi la loro ammirazione per lo show o per i suoi protagonisti.<\/p>\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_77 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Table of Contents<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Toggle Table of Content\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 eztoc-toggle-hide-by-default' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/thebiography.org\/it\/fatti-che-non-sapevi-sugli-impractical-jokers\/#Leducazione_di_un_burlone\" >L&#8217;educazione di un burlone<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/thebiography.org\/it\/fatti-che-non-sapevi-sugli-impractical-jokers\/#La_Nascita_dei_Tenderloins_e_degli_Impractical_Jokers\" >La Nascita dei Tenderloins e degli Impractical Jokers<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/thebiography.org\/it\/fatti-che-non-sapevi-sugli-impractical-jokers\/#Prima_di_%E2%80%98Impractical_Jokers\" >Prima di \u2018Impractical Jokers\u2019<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/thebiography.org\/it\/fatti-che-non-sapevi-sugli-impractical-jokers\/#Gli_scherzi_non_finiscono_mai\" >Gli scherzi non finiscono mai.<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/thebiography.org\/it\/fatti-che-non-sapevi-sugli-impractical-jokers\/#Accuse_di_Realta_Creativa\" >Accuse di Realt\u00e0 Creativa<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/thebiography.org\/it\/fatti-che-non-sapevi-sugli-impractical-jokers\/#Le_punizioni_possono_sfuggire_di_mano\" >Le punizioni possono sfuggire di mano.<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https:\/\/thebiography.org\/it\/fatti-che-non-sapevi-sugli-impractical-jokers\/#La_fidanzata_segreta_di_Quinn\" >La fidanzata segreta di Quinn<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-8\" href=\"https:\/\/thebiography.org\/it\/fatti-che-non-sapevi-sugli-impractical-jokers\/#Raffreddare_la_rabbia\" >Raffreddare la rabbia<\/a><\/li><\/ul><\/nav><\/div>\n<h2><span class=\"ez-toc-section\" id=\"Leducazione_di_un_burlone\"><\/span>L&#8217;educazione di un burlone<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Quando lo show suggeriva che The Tenderloins fossero amici da sempre, almeno quello non era un bugia. Le quattro stelle di \u2018Impractical Jokers\u2019 sono diventati amici durante l&#8217;adolescenza e, sebbene lo show non lo nasconda, ci sono ancora dettagli sulla loro amicizia tenuti nascosti al pubblico.<\/p>\n<p>https:\/\/www.facebook.com\/ImpracticalJokers\/photos\/4084631471575116<\/p>\n<p>Joe, Sal, James e Brian sono tutti cresciuti a Staten Island, New York, e venivano considerati i pagliacci e i burloni della loro classe alla Monsignor Farrel High School. La scuola cattolica per soli ragazzi \u00e8 diventata il banco di prova per i loro scherzi e il loro umorismo unico.<\/p>\n<p>Nonostante i loro comportamenti da adolescenti, nessuno di loro avrebbe mai creduto che un giorno avrebbero tratto un sostentamento prospero dalle loro bravate, tuttavia l&#8217;amicizia che avevano sviluppato allora si \u00e8 rivelata il loro pi\u00f9 grande successo nella vita.<\/p>\n<p>Mentre per alcuni potrebbe sembrare un sogno ridicolo, per loro \u00e8 diventata realt\u00e0. In un certo senso, il liceo li ha preparati per la loro futura carriera, sebbene ci\u00f2 possa essere avvenuto in modo non intenzionale. Molte delle burle che gli spettatori possono vedere nello show hanno tratto ispirazione dalle marachelle che hanno combinato al liceo, ma il percorso per raggiungere il successo che ora godono sarebbe stato piuttosto lungo.<\/p>\n<blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\">\n<p lang=\"en\" dir=\"ltr\">No goats were harmed in the making of this episode. <a rel=\"nofollow\" href=\"https:\/\/twitter.com\/hashtag\/ImpracticalJokers?src=hash&amp;ref_src=twsrc%5Etfw\">#ImpracticalJokers<\/a> <a rel=\"nofollow\" href=\"https:\/\/t.co\/sQH6hvzRob\">pic.twitter.com\/sQH6hvzRob<\/a><\/p>\n<p>&mdash; Impractical Jokers (@JokersTBS) <a rel=\"nofollow\" href=\"https:\/\/twitter.com\/JokersTBS\/status\/1375477753038966787?ref_src=twsrc%5Etfw\">March 26, 2021<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<h2><span class=\"ez-toc-section\" id=\"La_Nascita_dei_Tenderloins_e_degli_Impractical_Jokers\"><\/span>La Nascita dei Tenderloins e degli Impractical Jokers<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Il quartetto di \u2018Impractical Jokers\u2019 potrebbe aver scoperto la sua passione per l&#8217;umorismo e gli scherzi al liceo, ma per guadagnarsi da vivere con tali buffonate, ovviamente, \u00e8 necessario un pubblico. Nel 1999, i quattro amici crearono un gruppo comico e portarono il loro umorismo su vari palcoscenici. Chiamarono il loro gruppo di quattro persone The Tenderloins, e il nome rimase.<\/p>\n<p>Tuttavia, il loro vero successo \u00e8 arrivato con l&#8217;ideazione di \u2018Impractical Jokers\u2019, che ha richiesto del tempo per essere sviluppato e che quasi non \u00e8 arrivato sullo schermo. Gran parte della creazione di \u2018Impractical Jokers\u2019 \u00e8 stata resa possibile dal successo che The Tenderloins avevano ottenuto con \u2018It\u2019s Your Show\u2019. Il programma NBC, condotto da Carson Daly, permetteva ai creatori di video amatoriali di competere per un premio di $100.000, e nel 2007 hanno presentato un video che alla fine gli ha fatto vincere la competizione.<\/p>\n<p>Il loro video era una finta creazione su un teleshopping che vendeva al pubblico una macchina del tempo che prometteva di sistemare il passato degli acquirenti senza problemi.<\/p>\n<p><script async src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8220363953005131\" crossorigin=\"anonymous\"><\/script>\r\n<!-- TheBiography.org res2 -->\r\n<ins class=\"adsbygoogle\"\r\n     style=\"display:block\"\r\n     data-ad-client=\"ca-pub-8220363953005131\"\r\n     data-ad-slot=\"8502510853\"\r\n     data-ad-format=\"auto\"\r\n     data-full-width-responsive=\"true\"><\/ins>\r\n<script>\r\n     (adsbygoogle = window.adsbygoogle || []).push({});\r\n<\/script>\r\n<amp-ad layout=\"fixed-height\" height=300 type=\"adsense\" data-ad-client=\"ca-pub-8220363953005131\" data-ad-slot=\"8502510853\"><\/amp-ad>\r\n<\/p>\n<p>Invece di sperperare il premio in denaro, i quattro amici decisero di investire i soldi nella creazione di un loro programma televisivo. L&#8217;idea di \u2018Impractical Jokers\u2019, inizialmente intitolata \u2018Mission: Uncomfortable\u2019, \u00e8 nata mentre si divertivano giocando ai videogiochi.<\/p>\n<p>Considerarono di creare un programma di scherzi, ma a differenza di molti altri, il loro concept ribaltava l&#8217;idea contro lo scherzista stesso. Inizialmente, presentarono l&#8217;idea e il episodio pilota a Spike TV, che purtroppo non mostr\u00f2 alcun interesse a mandare in onda il programma. Nonostante il loro successivo successo su TruTV, i Tenderloins rimasero importanti per tutti loro, e continuano a esibirsi in spettacoli comici per coloro che preferiscono i loro talenti scenici rispetto agli scherzi della serie televisiva.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Prima_di_%E2%80%98Impractical_Jokers\"><\/span>Prima di \u2018Impractical Jokers\u2019<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Prima che tutti e quattro ottenessero successo in televisione, i quattro comici dovevano mantenere un lato normale della vita, almeno per continuare a pagare le bollette mentre sviluppavano il loro numero comico.<\/p>\n<p><iframe title=\"Impractical Jokers: Funniest Fast Food Moments (Mashup) | truTV\" width=\"770\" height=\"433\" src=\"https:\/\/www.youtube.com\/embed\/kb5iwtdSKYI?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n<p>Sebbene forse riluttanti ad ammetterlo, il gruppo degli \u2018Impractical Jokers\u2019 era composto da veri e propri nerd al liceo, e alcuni di loro hanno effettivamente ottenuto un notevole successo prima della creazione dello show. Sal, che considerano spesso il meno propenso dei quattro amici a portare a termine una sfida, giocava a scacchi per la sua scuola superiore, il che potrebbe essere la fonte della sua logica ferrea.<\/p>\n<p>A parte questo, Sal potrebbe essere anche l&#8217;unico sportivo tipico del gruppo, dato che ha giocato a football e a basket alle superiori e, dopo il diploma, ha conseguito una laurea in finanza alla St. John&#8217;s University di New York.<\/p>\n<p>James manifest\u00f2 interesse per il teatro e il bowling mentre frequentava le scuole superiori e, dopo la laurea, consegu\u00ec una laurea triennale in inglese. Murray continu\u00f2 a lavorare per la societ\u00e0 di produzione responsabile di \u2018Impractical Jokers\u2019, NorthSouth Productions, come loro senior VP dello sviluppo.<\/p>\n<figure id=\"attachment_7304\" aria-describedby=\"caption-attachment-7304\" style=\"width: 683px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-7304\" src=\"https:\/\/thebiography.org\/wp-content\/uploads\/2021\/03\/https___i.cdn_.tbs_.com_assets_images_2019_12_ImpracticalJokers-1024x1536_0-683x1024.jpg\" alt=\"\" width=\"683\" height=\"1024\" srcset=\"\/\/thebiography.org\/wp-content\/uploads\/2021\/03\/https___i.cdn_.tbs_.com_assets_images_2019_12_ImpracticalJokers-1024x1536_0-683x1024.jpg 683w, \/\/thebiography.org\/wp-content\/uploads\/2021\/03\/https___i.cdn_.tbs_.com_assets_images_2019_12_ImpracticalJokers-1024x1536_0-200x300.jpg 200w, \/\/thebiography.org\/wp-content\/uploads\/2021\/03\/https___i.cdn_.tbs_.com_assets_images_2019_12_ImpracticalJokers-1024x1536_0-175x263.jpg 175w, \/\/thebiography.org\/wp-content\/uploads\/2021\/03\/https___i.cdn_.tbs_.com_assets_images_2019_12_ImpracticalJokers-1024x1536_0-450x675.jpg 450w, \/\/thebiography.org\/wp-content\/uploads\/2021\/03\/https___i.cdn_.tbs_.com_assets_images_2019_12_ImpracticalJokers-1024x1536_0-768x1152.jpg 768w, \/\/thebiography.org\/wp-content\/uploads\/2021\/03\/https___i.cdn_.tbs_.com_assets_images_2019_12_ImpracticalJokers-1024x1536_0.jpg 1024w\" sizes=\"auto, (max-width: 683px) 100vw, 683px\" \/><figcaption id=\"caption-attachment-7304\" class=\"wp-caption-text\"><a href=\"https:\/\/images.tbs.com\/tbs\/%24dyna_params\/https%3A%2F%2Fi.cdn.tbs.com%2Fassets%2Fimages%2F2019%2F12%2FImpracticalJokers-1024x1536_0.jpg\" target=\"_blank\" rel=\"nofollow noopener\">Scherzi Impossibili<\/a><\/figcaption><\/figure>\n<p>Joe, il matematico del gruppo di amici, faceva parte del club di matematica della scuola superiore e in seguito si \u00e8 laureato in contabilit\u00e0 alla Long Island University.<\/p>\n<p>Quinn faceva parte della marching band del liceo e ha anche espresso interesse per la videografia. Dopo il liceo, Brian ha lavorato come pompiere per il corpo dei vigili del fuoco di New York City, ma quando hanno iniziato le riprese di \u2018Impractical Jokers\u2019, ha preso un congedo permanente dai suoi doveri di pompiere.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Gli_scherzi_non_finiscono_mai\"><\/span>Gli scherzi non finiscono mai.<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>I Tenderloins sono diventati famosi per i loro scherzi non convenzionali, che invece di cercare una vittima ignara tra il pubblico, si prendono in giro da soli. Tuttavia, il gruppo si \u00e8 fatto scherzi e ha ingannato l&#8217;un l&#8217;altro fin dai primi tempi della loro amicizia, durante l&#8217;adolescenza.<\/p>\n<p>Come molti hanno suggerito in passato, gli uomini semplicemente non crescono, e nonostante siano diventati adulti, sono tutt&#8217;altro che maturi tra di loro.<\/p>\n<p><script async src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8220363953005131\" crossorigin=\"anonymous\"><\/script>\r\n<!-- TheBiography.org res3 -->\r\n<ins class=\"adsbygoogle\"\r\n     style=\"display:block\"\r\n     data-ad-client=\"ca-pub-8220363953005131\"\r\n     data-ad-slot=\"1812684276\"\r\n     data-ad-format=\"auto\"\r\n     data-full-width-responsive=\"true\"><\/ins>\r\n<script>\r\n     (adsbygoogle = window.adsbygoogle || []).push({});\r\n<\/script>\r\n<amp-ad layout=\"fixed-height\" height=300 type=\"adsense\" data-ad-client=\"ca-pub-8220363953005131\" data-ad-slot=\"1812684276\"><\/amp-ad>\r\n<\/p>\n<p>Sfortunatamente, i fan pi\u00f9 accaniti di \u2018Impractical Jokers\u2019 non possono vedere ogni piccolo scherzo che si fanno l&#8217;un l&#8217;altro, dato che gli scherzi continuano ben dopo che le telecamere hanno smesso di riprendere. In un&#8217;intervista con \u2018Comedy Central UK\u2019, il gruppo ha ammesso di continuare a scherzarsi a vicenda, come facevano ai tempi del liceo, e ha persino discusso in dettaglio tutte le cose spiacevoli che si fanno a vicenda.<\/p>\n<p>Non sorprende che la vittima pi\u00f9 grande dello show, Murray, sia anche il loro preferito per gli scherzi fuori dalle telecamere. Gli altri hanno ammesso che uno dei loro scherzi preferiti \u00e8 quello di indurre Murray a lasciare una mancia pi\u00f9 alta nei ristoranti, spesso distraendolo per aggiungere cifre ai conti.<\/p>\n<p>Secondo loro, gli scherzi sono diventati la base della loro amicizia, e tutto avviene per divertimento, anche se quando si tratta di sfidare Joe, il gruppo ha imparato la lezione e raramente oserebbe chiedergli di fare qualcosa. Di gran lunga il temerario pi\u00f9 coraggioso tra loro, Joe sarebbe disposto a fare praticamente qualsiasi cosa.<\/p>\n<div id='gallery-2' class='gallery galleryid-75590 gallery-columns-4 gallery-size-thumbnail'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/thebiography.org\/wp-content\/uploads\/2021\/03\/GettyImages-997246838.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"data:image\/svg+xml;base64,PHN2ZyB2aWV3Qm94PScwIDAgMTUwIDE1MCcgeG1sbnM9J2h0dHA6Ly93d3cudzMub3JnLzIwMDAvc3ZnJz48L3N2Zz4=\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-src=\"https:\/\/thebiography.org\/wp-content\/uploads\/2021\/03\/GettyImages-997246838-150x150.jpg\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/thebiography.org\/wp-content\/uploads\/2021\/03\/710nt6P9WgL._RI_.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"data:image\/svg+xml;base64,PHN2ZyB2aWV3Qm94PScwIDAgMTUwIDE1MCcgeG1sbnM9J2h0dHA6Ly93d3cudzMub3JnLzIwMDAvc3ZnJz48L3N2Zz4=\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-src=\"https:\/\/thebiography.org\/wp-content\/uploads\/2021\/03\/710nt6P9WgL._RI_-150x150.jpg\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/thebiography.org\/wp-content\/uploads\/2021\/03\/impractical-jokers-712951_1253_r.jpeg.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"data:image\/svg+xml;base64,PHN2ZyB2aWV3Qm94PScwIDAgMTUwIDE1MCcgeG1sbnM9J2h0dHA6Ly93d3cudzMub3JnLzIwMDAvc3ZnJz48L3N2Zz4=\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-src=\"https:\/\/thebiography.org\/wp-content\/uploads\/2021\/03\/impractical-jokers-712951_1253_r.jpeg-150x150.jpg\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/thebiography.org\/wp-content\/uploads\/2021\/03\/1_uOkb_fXnbSMI8-i1Y5iIvA.jpeg'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"data:image\/svg+xml;base64,PHN2ZyB2aWV3Qm94PScwIDAgMTUwIDE1MCcgeG1sbnM9J2h0dHA6Ly93d3cudzMub3JnLzIwMDAvc3ZnJz48L3N2Zz4=\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-src=\"https:\/\/thebiography.org\/wp-content\/uploads\/2021\/03\/1_uOkb_fXnbSMI8-i1Y5iIvA-150x150.jpeg\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\n<h2><span class=\"ez-toc-section\" id=\"Accuse_di_Realta_Creativa\"><\/span>Accuse di Realt\u00e0 Creativa<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Quasi ogni reality show si \u00e8 trovato ad affrontare accuse di disonest\u00e0, il che dimostra, in definitiva, quanto siano diffidenti gli spettatori nei confronti di ci\u00f2 che stanno guardando. Considerando che il montaggio e altre manipolazioni della realt\u00e0 hanno influenzato molti programmi, e che numerosi reality show sono colpevoli di produrre realt\u00e0 creative o scritte, i fan hanno motivo di dubitare dei loro programmi preferiti. &#8216;Impractical Jokers&#8217; non \u00e8 estraneo a tali accuse, ed \u00e8 logico pensare che ci siano molte motivazioni dietro alcune delle affermazioni fatte contro il programma.<\/p>\n<p>Alcune accuse si basano sulla natura inverosimile degli scherzi nello show, che per alcuni sembrano lontani dalla realt\u00e0. Un altro motivo per cui i fan spesso mettono in discussione lo show deriva dal fatto che, nonostante la loro fama, il pubblico ignaro che collabora ai loro scherzi non li riconosce mai. Naturalmente, molte persone hanno effettivamente capito chi fossero, occasionalmente in momenti in cui non stavano filmando.<\/p>\n<figure id=\"attachment_7305\" aria-describedby=\"caption-attachment-7305\" style=\"width: 683px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-7305\" src=\"https:\/\/thebiography.org\/wp-content\/uploads\/2021\/03\/MV5BYTAzMmIwMWQtYjRjYy00NmM2LWIxYWUtY2NhYjMzZjc4ZGZmXkEyXkFqcGdeQXVyNDc3MzQ5Nzc@._V1_-683x1024.jpg\" alt=\"\" width=\"683\" height=\"1024\" srcset=\"\/\/thebiography.org\/wp-content\/uploads\/2021\/03\/MV5BYTAzMmIwMWQtYjRjYy00NmM2LWIxYWUtY2NhYjMzZjc4ZGZmXkEyXkFqcGdeQXVyNDc3MzQ5Nzc@._V1_-683x1024.jpg 683w, \/\/thebiography.org\/wp-content\/uploads\/2021\/03\/MV5BYTAzMmIwMWQtYjRjYy00NmM2LWIxYWUtY2NhYjMzZjc4ZGZmXkEyXkFqcGdeQXVyNDc3MzQ5Nzc@._V1_-200x300.jpg 200w, \/\/thebiography.org\/wp-content\/uploads\/2021\/03\/MV5BYTAzMmIwMWQtYjRjYy00NmM2LWIxYWUtY2NhYjMzZjc4ZGZmXkEyXkFqcGdeQXVyNDc3MzQ5Nzc@._V1_-175x263.jpg 175w, \/\/thebiography.org\/wp-content\/uploads\/2021\/03\/MV5BYTAzMmIwMWQtYjRjYy00NmM2LWIxYWUtY2NhYjMzZjc4ZGZmXkEyXkFqcGdeQXVyNDc3MzQ5Nzc@._V1_-450x675.jpg 450w, \/\/thebiography.org\/wp-content\/uploads\/2021\/03\/MV5BYTAzMmIwMWQtYjRjYy00NmM2LWIxYWUtY2NhYjMzZjc4ZGZmXkEyXkFqcGdeQXVyNDc3MzQ5Nzc@._V1_-768x1152.jpg 768w, \/\/thebiography.org\/wp-content\/uploads\/2021\/03\/MV5BYTAzMmIwMWQtYjRjYy00NmM2LWIxYWUtY2NhYjMzZjc4ZGZmXkEyXkFqcGdeQXVyNDc3MzQ5Nzc@._V1_.jpg 900w\" sizes=\"auto, (max-width: 683px) 100vw, 683px\" \/><figcaption id=\"caption-attachment-7305\" class=\"wp-caption-text\"><a href=\"https:\/\/m.media-amazon.com\/images\/M\/MV5BYTAzMmIwMWQtYjRjYy00NmM2LWIxYWUtY2NhYjMzZjc4ZGZmXkEyXkFqcGdeQXVyNDc3MzQ5Nzc@._V1_.jpg\" target=\"_blank\" rel=\"nofollow noopener\">Scherzi Impossibili<\/a><\/figcaption><\/figure>\n<p>I membri della troupe hanno ammesso che sconosciuti li avvicinano frequentemente in pubblico e li accusano di fare uno scherzo, anche quando non ci sono telecamere da nessuna parte nelle vicinanze. Spesso vengono riconosciuti, ma poich\u00e9 questi scherzi sono considerati falliti, gli spettatori semplicemente non li vedono come parte di un episodio, soprattutto perch\u00e9 risulterebbero privi di intrattenimento. Tuttavia, il principale sospetto tra i fan deriva dalla possibilit\u00e0 che il programma assuma comparse come membri del pubblico.<\/p>\n<p>Alcuni fan attenti hanno notato che le stesse persone appaiono spesso in background, o come parte del pubblico ignaro, il che ovviamente ha sollevato dei dubbi. Rispondendo a queste accuse, Quinn ha affermato che non usano attori, ma piuttosto persone che partecipano a focus group. Sorprendentemente, a volte le stesse persone si presentano, ma in qualche modo non si accorgono mai di apparire nello show.<\/p>\n<p>Sebbene sia una scusa plausibile e accettabile, molti fan semplicemente non ci credono.<\/p>\n<p>https:\/\/www.instagram.com\/p\/CM3UkyJo2eX\/<\/p>\n<p>Tuttavia, prove inconfutabili devono ancora essere presentate, ma fino ad allora, i fan vogliono credere che \u2018Impractical Jokers\u2019 presenti solo pura realt\u00e0.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Le_punizioni_possono_sfuggire_di_mano\"><\/span>Le punizioni possono sfuggire di mano.<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Dato che lo show di solito occupa solo trenta minuti di programmazione su TruTV, i fan e gli spettatori non sempre riescono a vedere l&#8217;intera punizione a cui viene sottoposto lo sfidante perdente, e che deve sopportare. Durante la maggior parte degli episodi, la punizione dura gli ultimi tre-dieci minuti, ma spesso il perdente deve sopportare ore di tormento.<\/p>\n<p>Un esempio di ci\u00f2 fu la ormai famosa punizione di Murray con il paracadutismo. Gli spettatori videro solo pochi momenti del suo terrore mentre si lanciava dall&#8217;aereo, e naturalmente il suo sudore persistente prima di salire sull&#8217;aeroplano. Tuttavia, gli spettatori non videro Murray mentre si rinchiudeva in un bagno per ore, inviando i suoi ultimi saluti a familiari e amici, credendo sinceramente di poter morire per la caduta.<\/p>\n<p>Un altro esempio di terrore prolungato di cui gli spettatori hanno intravisto solo un frammento \u00e8 stata la punizione di Sal quando ha dovuto fingere di essere un sensitivo.<\/p>\n<p><script async src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8220363953005131\" crossorigin=\"anonymous\"><\/script>\r\n<!-- TheBiography.org res4 -->\r\n<ins class=\"adsbygoogle\"\r\n     style=\"display:block\"\r\n     data-ad-client=\"ca-pub-8220363953005131\"\r\n     data-ad-slot=\"7189429181\"\r\n     data-ad-format=\"auto\"\r\n     data-full-width-responsive=\"true\"><\/ins>\r\n<script>\r\n     (adsbygoogle = window.adsbygoogle || []).push({});\r\n<\/script>\r\n<amp-ad layout=\"fixed-height\" height=300 type=\"adsense\" data-ad-client=\"ca-pub-8220363953005131\" data-ad-slot=\"7189429181\"><\/amp-ad>\r\n<\/p>\n<p>Lo spettacolo ha trasmesso solo tre minuti di alcune delle migliori improvvisazioni che Sal abbia mai fatto in vita sua, ma in realt\u00e0, doveva intrattenere un pubblico di 200 persone per almeno un&#8217;ora. Una delle punizioni pi\u00f9 esagerate include anche il momento in cui hanno fatto credere a Sal qualcosa che non era mai vero, per otto mesi.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"La_fidanzata_segreta_di_Quinn\"><\/span>La fidanzata segreta di Quinn<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Nonostante l&#8217;intento ottimista di Quinn di mantenere segreta l&#8217;identit\u00e0 di una delle sue fidanzate, alcuni Redditor e fan dediti hanno scoperto chi potrebbe essere. Ricavando informazioni da certe cose che Brian ha lasciato trapelare su di lei durante lo show, i detective di Reddit hanno scoperto che in passato aveva frequentato la sorellastra di una celebrit\u00e0 di prima grandezza.<\/p>\n<p>Poich\u00e9 la sua famiglia si trov\u00f2 in una situazione piuttosto compromettente e delicata, Quinn non rivel\u00f2 mai la sua vera identit\u00e0, tuttavia, menzion\u00f2 di aver scontato una pena per una violazione penale. Utilizzando queste informazioni e confrontandole con la cronologia fornita, gli utenti di Reddit determinarono che l&#8217;unica persona possibile fosse Elizabeth, la sorellastra della star di \u2018King of Queens\u2019, Leah Remini.<\/p>\n<p><iframe title=\"Impractical Jokers - Q&#039;s Most Romantic Moments\" width=\"770\" height=\"433\" src=\"https:\/\/www.youtube.com\/embed\/egqt9KL3cyk?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n<p>La polizia arrest\u00f2 Elizabeth nel 2005 per traffico di stupefacenti, ma i loro risultati non sono altro che speculazioni che potrebbero non essere mai confermate. A parte questo, non \u00e8 mai stato confermato chi potesse essere la ragazza segreta di Quinn.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Raffreddare_la_rabbia\"><\/span>Raffreddare la rabbia<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>In numerose occasioni, alcuni membri della compagnia, a causa degli scherzi del gruppo, hanno perso completamente il controllo, arrivando persino a reagire fisicamente dopo essere stati presi in giro. A titolo di esempio, molti fan ricordano l&#8217;esperienza di Joe in uno stadio di baseball, quando si dedic\u00f2 a rubare palle da baseball firmate a bambini ignari.<\/p>\n<p>Quello che molti fan non hanno mai visto \u00e8 quanto una mamma si sia arrabbiata con Joe al punto da arrivare quasi ad aggredire il burlone, ma in sua difesa, lui in un certo senso se l&#8217;era cercata.<\/p>\n<p>Tuttavia, i fan si sono chiesti cosa faccia lo show e i burloni per convincere i loro obiettivi a comparire in camera, suggerendo che li paghino per placare la loro rabbia.<\/p>\n<p>https:\/\/www.facebook.com\/ImpracticalJokers\/photos\/2663955546976056<\/p>\n<p>Dato che ogni persona che appare nello show deve fornire il consenso firmato, spesso \u00e8 necessario molto convincimento per ottenere il loro accordo, specialmente se sono stati infuriati da uno scherzo specifico. Sembra, tuttavia, che i fan non si siano sbagliati nel loro suggerimento.<\/p>\n<p>Durante una sessione di domande e risposte su Reddit, Sal ha ammesso che, quando non c&#8217;era altra scelta, e soprattutto se la reazione del partecipante sembrava degna, li avrebbe pagati per la loro partecipazione allo show. Tuttavia, la maggior parte delle volte il pubblico ignaro acconsente per gentilezza o per ottenere i suoi cinque minuti di fama.<\/p>\n<p>Se nessuno di questi fatti ti dissuade dal goderti \u2018Impractical Jokers\u2019, allora sentiti libero di vedere l&#8217;ultima puntata. Almeno dovrebbe valere qualche risata e non \u00e8 il modo peggiore per passare il tempo. Se non ne hai proprio abbastanza di The Tenderloins, puoi guardare il loro lungometraggio o uno qualsiasi dei loro canali YouTube e podcast dedicati. Potresti anche dare un&#8217;occhiata ai loro spettacoli dal vivo, a meno che non siano solo gli scherzi a tenerti intrigato.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Fatti che non sapevi sugli Impractical JokersMolti considererebbero la risata universale, e potrebbero non avere torto, soprattutto considerando la popolarit\u00e0 di alcuni programmi comici e dei video virali su internet. Naturalmente, non c&#8217;\u00e8 modo migliore per godersi il tempo libero che ridere di qualcosa che vale una risata. Sapendo questo, NorthSouth Productions ha creato la<\/p>\n","protected":false},"author":1,"featured_media":7303,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ep_exclude_from_search":false,"amp_status":"","footnotes":""},"categories":[6659],"tags":[],"class_list":{"0":"post-75590","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-elenchi"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Fatti che non sapevi sugli Impractical Jokers<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/thebiography.org\/it\/fatti-che-non-sapevi-sugli-impractical-jokers\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fatti che non sapevi sugli Impractical Jokers\" \/>\n<meta property=\"og:description\" content=\"Fatti che non sapevi sugli Impractical JokersMolti considererebbero la risata universale, e potrebbero non avere torto, soprattutto considerando la popolarit\u00e0 di alcuni programmi comici e dei video virali su internet. Naturalmente, non c&#8217;\u00e8 modo migliore per godersi il tempo libero che ridere di qualcosa che vale una risata. Sapendo questo, NorthSouth Productions ha creato la\" \/>\n<meta property=\"og:url\" content=\"https:\/\/thebiography.org\/it\/fatti-che-non-sapevi-sugli-impractical-jokers\/\" \/>\n<meta property=\"og:site_name\" content=\"The Biography\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/daniel.wanburg\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-09-11T05:47:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/thebiography.org\/wp-content\/uploads\/2021\/03\/F5OUDQCY6XJITOLPRRVLMO3UZQ.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Daniel Wanburg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Daniel Wanburg\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"13 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/thebiography.org\/it\/fatti-che-non-sapevi-sugli-impractical-jokers\/\",\"url\":\"https:\/\/thebiography.org\/it\/fatti-che-non-sapevi-sugli-impractical-jokers\/\",\"name\":\"Fatti che non sapevi sugli Impractical Jokers\",\"isPartOf\":{\"@id\":\"https:\/\/thebiography.org\/it\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/thebiography.org\/it\/fatti-che-non-sapevi-sugli-impractical-jokers\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/thebiography.org\/it\/fatti-che-non-sapevi-sugli-impractical-jokers\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/thebiography.org\/wp-content\/uploads\/2021\/03\/F5OUDQCY6XJITOLPRRVLMO3UZQ.jpg\",\"datePublished\":\"2025-09-11T05:47:02+00:00\",\"author\":{\"@id\":\"https:\/\/thebiography.org\/it\/#\/schema\/person\/1d126e3e6e3c48b3ff869d116a4fbc1c\"},\"breadcrumb\":{\"@id\":\"https:\/\/thebiography.org\/it\/fatti-che-non-sapevi-sugli-impractical-jokers\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/thebiography.org\/it\/fatti-che-non-sapevi-sugli-impractical-jokers\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/thebiography.org\/it\/fatti-che-non-sapevi-sugli-impractical-jokers\/#primaryimage\",\"url\":\"https:\/\/thebiography.org\/wp-content\/uploads\/2021\/03\/F5OUDQCY6XJITOLPRRVLMO3UZQ.jpg\",\"contentUrl\":\"https:\/\/thebiography.org\/wp-content\/uploads\/2021\/03\/F5OUDQCY6XJITOLPRRVLMO3UZQ.jpg\",\"width\":1200,\"height\":600,\"caption\":\"Impractical Jokers\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/thebiography.org\/it\/fatti-che-non-sapevi-sugli-impractical-jokers\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/thebiography.org\/it\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Fatti che non sapevi sugli Impractical Jokers\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/thebiography.org\/it\/#website\",\"url\":\"https:\/\/thebiography.org\/it\/\",\"name\":\"The Biography\",\"description\":\"Relationships, Net Worth, Measurements\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/thebiography.org\/it\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/thebiography.org\/it\/#\/schema\/person\/1d126e3e6e3c48b3ff869d116a4fbc1c\",\"name\":\"Daniel Wanburg\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/thebiography.org\/it\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/ea3e6e37b405aa3457baa18b3ae51ab5564d43737a0427463d5d20892d4d11b9?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/ea3e6e37b405aa3457baa18b3ae51ab5564d43737a0427463d5d20892d4d11b9?s=96&d=mm&r=g\",\"caption\":\"Daniel Wanburg\"},\"description\":\"As Managing Editor at The Biography, I oversee a skilled team to produce insightful biographies of influential figures. My responsibilities include managing the editorial process, conducting detailed research, crafting engaging narratives, and ensuring the accuracy and quality of our content. At The Biography, we aim to deliver in-depth profiles that provide valuable insights into the realms of business, entertainment, and more. Our commitment to meticulous research and dynamic storytelling highlights the significant journeys and successes of inspiring individuals.\",\"sameAs\":[\"https:\/\/www.facebook.com\/daniel.wanburg\/\",\"https:\/\/www.linkedin.com\/in\/daniel-wanburg-618177164\/\"],\"url\":\"https:\/\/thebiography.org\/it\/author\/admin\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Fatti che non sapevi sugli Impractical Jokers","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/thebiography.org\/it\/fatti-che-non-sapevi-sugli-impractical-jokers\/","og_locale":"it_IT","og_type":"article","og_title":"Fatti che non sapevi sugli Impractical Jokers","og_description":"Fatti che non sapevi sugli Impractical JokersMolti considererebbero la risata universale, e potrebbero non avere torto, soprattutto considerando la popolarit\u00e0 di alcuni programmi comici e dei video virali su internet. Naturalmente, non c&#8217;\u00e8 modo migliore per godersi il tempo libero che ridere di qualcosa che vale una risata. Sapendo questo, NorthSouth Productions ha creato la","og_url":"https:\/\/thebiography.org\/it\/fatti-che-non-sapevi-sugli-impractical-jokers\/","og_site_name":"The Biography","article_author":"https:\/\/www.facebook.com\/daniel.wanburg\/","article_published_time":"2025-09-11T05:47:02+00:00","og_image":[{"width":1200,"height":600,"url":"https:\/\/thebiography.org\/wp-content\/uploads\/2021\/03\/F5OUDQCY6XJITOLPRRVLMO3UZQ.jpg","type":"image\/jpeg"}],"author":"Daniel Wanburg","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Daniel Wanburg","Est. reading time":"13 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/thebiography.org\/it\/fatti-che-non-sapevi-sugli-impractical-jokers\/","url":"https:\/\/thebiography.org\/it\/fatti-che-non-sapevi-sugli-impractical-jokers\/","name":"Fatti che non sapevi sugli Impractical Jokers","isPartOf":{"@id":"https:\/\/thebiography.org\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/thebiography.org\/it\/fatti-che-non-sapevi-sugli-impractical-jokers\/#primaryimage"},"image":{"@id":"https:\/\/thebiography.org\/it\/fatti-che-non-sapevi-sugli-impractical-jokers\/#primaryimage"},"thumbnailUrl":"https:\/\/thebiography.org\/wp-content\/uploads\/2021\/03\/F5OUDQCY6XJITOLPRRVLMO3UZQ.jpg","datePublished":"2025-09-11T05:47:02+00:00","author":{"@id":"https:\/\/thebiography.org\/it\/#\/schema\/person\/1d126e3e6e3c48b3ff869d116a4fbc1c"},"breadcrumb":{"@id":"https:\/\/thebiography.org\/it\/fatti-che-non-sapevi-sugli-impractical-jokers\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/thebiography.org\/it\/fatti-che-non-sapevi-sugli-impractical-jokers\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/thebiography.org\/it\/fatti-che-non-sapevi-sugli-impractical-jokers\/#primaryimage","url":"https:\/\/thebiography.org\/wp-content\/uploads\/2021\/03\/F5OUDQCY6XJITOLPRRVLMO3UZQ.jpg","contentUrl":"https:\/\/thebiography.org\/wp-content\/uploads\/2021\/03\/F5OUDQCY6XJITOLPRRVLMO3UZQ.jpg","width":1200,"height":600,"caption":"Impractical Jokers"},{"@type":"BreadcrumbList","@id":"https:\/\/thebiography.org\/it\/fatti-che-non-sapevi-sugli-impractical-jokers\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/thebiography.org\/it\/"},{"@type":"ListItem","position":2,"name":"Fatti che non sapevi sugli Impractical Jokers"}]},{"@type":"WebSite","@id":"https:\/\/thebiography.org\/it\/#website","url":"https:\/\/thebiography.org\/it\/","name":"The Biography","description":"Relationships, Net Worth, Measurements","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/thebiography.org\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/thebiography.org\/it\/#\/schema\/person\/1d126e3e6e3c48b3ff869d116a4fbc1c","name":"Daniel Wanburg","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/thebiography.org\/it\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/ea3e6e37b405aa3457baa18b3ae51ab5564d43737a0427463d5d20892d4d11b9?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ea3e6e37b405aa3457baa18b3ae51ab5564d43737a0427463d5d20892d4d11b9?s=96&d=mm&r=g","caption":"Daniel Wanburg"},"description":"As Managing Editor at The Biography, I oversee a skilled team to produce insightful biographies of influential figures. My responsibilities include managing the editorial process, conducting detailed research, crafting engaging narratives, and ensuring the accuracy and quality of our content. At The Biography, we aim to deliver in-depth profiles that provide valuable insights into the realms of business, entertainment, and more. Our commitment to meticulous research and dynamic storytelling highlights the significant journeys and successes of inspiring individuals.","sameAs":["https:\/\/www.facebook.com\/daniel.wanburg\/","https:\/\/www.linkedin.com\/in\/daniel-wanburg-618177164\/"],"url":"https:\/\/thebiography.org\/it\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/thebiography.org\/it\/wp-json\/wp\/v2\/posts\/75590","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/thebiography.org\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/thebiography.org\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/thebiography.org\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/thebiography.org\/it\/wp-json\/wp\/v2\/comments?post=75590"}],"version-history":[{"count":0,"href":"https:\/\/thebiography.org\/it\/wp-json\/wp\/v2\/posts\/75590\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/thebiography.org\/it\/wp-json\/wp\/v2\/media\/7303"}],"wp:attachment":[{"href":"https:\/\/thebiography.org\/it\/wp-json\/wp\/v2\/media?parent=75590"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/thebiography.org\/it\/wp-json\/wp\/v2\/categories?post=75590"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/thebiography.org\/it\/wp-json\/wp\/v2\/tags?post=75590"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}